{"id":97066,"date":"2023-03-03T18:38:01","date_gmt":"2023-03-03T17:38:01","guid":{"rendered":"https:\/\/www.fisifvg.org\/?p=97066"},"modified":"2023-03-03T18:38:01","modified_gmt":"2023-03-03T17:38:01","slug":"la-start-list-della-fase-regionale-del-trofeo-delle-societa-a-piancavallo","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2023\/03\/03\/la-start-list-della-fase-regionale-del-trofeo-delle-societa-a-piancavallo\/","title":{"rendered":"La start list della fase regionale del Trofeo delle Societ\u00e0 a Piancavallo"},"content":{"rendered":"<p>\u00c8 lo Sci Club Pordenone l\u2019organizzatore della fase regionale del Trofeo delle Societ\u00e0 2023.<\/p>\n<p>L\u2019appuntamento \u00e8 sabato 4 marzo a Piancavallo, giorno nel quale si svolger\u00e0 anche un altro gigante del circuito FISI FVG Giovani, Senior e Master.<\/p>\n<p>La prima gara assegner\u00e0 il Trofeo Master Sport, la seconda il Trofeo Pandam.<\/p>\n<p>Ricordiamo che la finale nazionale \u00e8 prevista il 2 aprile all&#8217;Abetone, in Toscana.<\/p>\n<p>Sotto le start list, si parte alle 9.<\/p>\n<p><a href=\"http:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/ODP-Trofeo-Master-Sport-.pdf\">START LIST GIGANTE 1<\/a><br \/>\n<a href=\"http:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/ODP-Trofeo-Pandam.pdf\">START LIST GIGANTE 2<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabato 4 marzo anche un secondo gigante valido per il circuito regionale<\/p>\n","protected":false},"author":4,"featured_media":46399,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,15],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/97066"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=97066"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/97066\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/46399"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=97066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=97066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=97066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}