{"id":97052,"date":"2023-03-03T13:53:20","date_gmt":"2023-03-03T12:53:20","guid":{"rendered":"https:\/\/www.fisifvg.org\/?p=97052"},"modified":"2023-03-03T13:53:20","modified_gmt":"2023-03-03T12:53:20","slug":"beatrice-rosca-trionfa-nel-gigante-del-gp-italia-giovani-sullo-zoncolan","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2023\/03\/03\/beatrice-rosca-trionfa-nel-gigante-del-gp-italia-giovani-sullo-zoncolan\/","title":{"rendered":"Beatrice Rosca trionfa nel gigante del GP Italia Giovani sullo Zoncolan"},"content":{"rendered":"<p>Si \u00e8 svolto oggi sullo Zoncolan il gigante del Gran Premio Italia Giovani Dicoflor femminile di sci alpino, organizzato, cos\u00ec come lo slalom di ieri, dal Cimenti Sci Carnia, che ha messo in palio il Gran Premio PrimaCassa.<\/p>\n<p>\u00c8 arrivata la splendida vittoria di Beatrice Rosca, che con il pettorale 20 ha ottenuto il quarto tempo nella prima manche e poi nella seconda ha rimontato fino a conquistato un grande successo, considerando che erano presenti le ragazze della squadra nazionale C.<\/p>\n<p>La 19enne della squadra FISI FVG, allenata allo SK Devin da Ales Sever, ha preceduto di 0&#8243;14 Alice Pazzaglia e di 0&#8243;53 Matilde Lorenzi. Sesta a 0&#8243;75 la compagna di squadra Caterina Sinigoi, seconda nella graduatoria del GP Italia alle spalle proprio di Bea. Una gran doppietta davvero.<br \/>\nSettima a 0&#8243;87 Andrea Craievich, azzurra dello Sci Club 70, autrice del miglior tempo nella seconda manche.<\/p>\n<p>Da segnalare anche il nono posto Aspiranti di Ginevra Quinz del Bachmann Sport College.<\/p>\n<p><a href=\"http:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/Classifica-ufficialeGS.pdf\">CLASSIFICA<\/a><br \/>\n<a href=\"http:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/Classifica-PREMI.pdf\">CLASSIFICA CATEGORIE<\/a><\/p>\n<div id='gallery-1' class='gallery galleryid-97052 gallery-columns-1 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2023\/03\/03\/beatrice-rosca-trionfa-nel-gigante-del-gp-italia-giovani-sullo-zoncolan\/whatsapp-image-2023-03-03-at-13-29-16-1\/'><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.29.16-1.jpeg\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-1-97082\" srcset=\"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.29.16-1.jpeg 1600w, https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.29.16-1-300x225.jpeg 300w, https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.29.16-1-1024x768.jpeg 1024w, https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.29.16-1-768x576.jpeg 768w, https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.29.16-1-1536x1152.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-97082'>\n\t\t\t\tCLASSIFICA ASSOLUTA\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2023\/03\/03\/beatrice-rosca-trionfa-nel-gigante-del-gp-italia-giovani-sullo-zoncolan\/whatsapp-image-2023-03-03-at-13-29-17\/'><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.29.17.jpeg\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-1-97081\" srcset=\"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.29.17.jpeg 1600w, https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.29.17-300x225.jpeg 300w, https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.29.17-1024x768.jpeg 1024w, https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.29.17-768x576.jpeg 768w, https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.29.17-1536x1152.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-97081'>\n\t\t\t\tCLASSIFICA GIOVANI\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2023\/03\/03\/beatrice-rosca-trionfa-nel-gigante-del-gp-italia-giovani-sullo-zoncolan\/whatsapp-image-2023-03-03-at-13-29-16\/'><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.29.16.jpeg\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-1-97083\" srcset=\"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.29.16.jpeg 1600w, https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.29.16-300x225.jpeg 300w, https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.29.16-1024x768.jpeg 1024w, https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.29.16-768x576.jpeg 768w, https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.29.16-1536x1152.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-97083'>\n\t\t\t\tCLASSIFICA ASPIRANTI\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2023\/03\/03\/beatrice-rosca-trionfa-nel-gigante-del-gp-italia-giovani-sullo-zoncolan\/whatsapp-image-2023-03-03-at-13-18-30\/'><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"721\" src=\"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.18.30.jpeg\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-1-97080\" srcset=\"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.18.30.jpeg 1600w, https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.18.30-300x135.jpeg 300w, https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.18.30-1024x461.jpeg 1024w, https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.18.30-768x346.jpeg 768w, https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-13.18.30-1536x692.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-97080'>\n\t\t\t\tda sinistra ROSCA, SEVER e SINIGOI\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2023\/03\/03\/beatrice-rosca-trionfa-nel-gigante-del-gp-italia-giovani-sullo-zoncolan\/whatsapp-image-2023-03-03-at-16-06-16\/'><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1600\" src=\"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-16.06.16.jpeg\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-1-97132\" srcset=\"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-16.06.16.jpeg 1200w, https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-16.06.16-225x300.jpeg 225w, https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-16.06.16-768x1024.jpeg 768w, https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/03\/WhatsApp-Image-2023-03-03-at-16.06.16-1152x1536.jpeg 1152w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-97132'>\n\t\t\t\tBEATRICE ROSCA\n\t\t\t\t<\/dd><\/dl>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Il Gran Premio PrimaCassa \u00e8 stato messo in palio dal Cimenti Sci Carnia. Bene anche Caterina Sinigoi, seconda nella graduatoria del circuito federale<\/p>\n","protected":false},"author":4,"featured_media":97079,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,15],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/97052"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=97052"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/97052\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/97079"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=97052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=97052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=97052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}