{"id":95036,"date":"2023-02-02T09:02:56","date_gmt":"2023-02-02T08:02:56","guid":{"rendered":"https:\/\/www.fisifvg.org\/?p=95036"},"modified":"2023-02-02T09:02:56","modified_gmt":"2023-02-02T08:02:56","slug":"a-tarvisio-i-campionati-italiani-u12-e-la-coppa-italia-u10-e-u14-di-salto-e-combinata","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2023\/02\/02\/a-tarvisio-i-campionati-italiani-u12-e-la-coppa-italia-u10-e-u14-di-salto-e-combinata\/","title":{"rendered":"A Tarvisio i Campionati Italiani U12 e la Coppa Italia U10 e U14 di salto e combinata"},"content":{"rendered":"<p>Domenica 19 febbraio Tarvisio ospiter\u00e0 i Campionati Italiani U12 di salto e combinata nordica; in contemporanea si svolger\u00e0 una tappa della Coppa Italia U10 e U14.<\/p>\n<p>L\u2019organizzazione, naturalmente, \u00e8 affidata allo Sci CAI Monte Lussari, che mette in palio il Trofeo De Martiis.<\/p>\n<p>Le gare di salto si svolgeranno dai trampolini HS36 e HS25 a partire dalle 9.30.<\/p>\n<p>Seguiranno dalle 13.30 le prove di fondo all\u2019Arena Paruzzi, su diverse distanze a seconda delle categorie.<\/p>\n<p>Sotto tutte le informazioni.<\/p>\n<p><a href=\"http:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2023\/02\/REGOLAMENTO-19-02-2023.pdf\">REGOLAMENTO<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019organizzazione \u00e8 affidata allo Sci CAI Monte Lussari, che mette in palio il Trofeo De Martiis<\/p>\n","protected":false},"author":4,"featured_media":75983,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14,10,12],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/95036"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=95036"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/95036\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/75983"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=95036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=95036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=95036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}