{"id":91420,"date":"2022-11-11T16:17:32","date_gmt":"2022-11-11T15:17:32","guid":{"rendered":"https:\/\/www.fisifvg.org\/?p=91420"},"modified":"2022-11-11T16:17:32","modified_gmt":"2022-11-11T15:17:32","slug":"coradazzi-primo-azzurro-nel-test-di-fondo-a-davos-top-10-per-di-centa-e-pittin","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2022\/11\/11\/coradazzi-primo-azzurro-nel-test-di-fondo-a-davos-top-10-per-di-centa-e-pittin\/","title":{"rendered":"Coradazzi primo azzurro nel test di fondo a Davos, top 10 per Di Centa e Pittin"},"content":{"rendered":"<p>Fondisti di Italia, Francia, Svizzera, Canada, Liechtenstein e Germania hanno preso parte a Davos (Svizzera) ad una gara sulla lunghezza di 11,5 km in tecnica classica che ha dato buone indicazioni alle formazioni azzurre, presenti con i gruppi di Milano-Cortina 2026, under 23 e osservati.<\/p>\n<p>La classifica finale maschiel vede sette transalpini ai primi sette posti, con Arnaud Chautemps vicitore in 27\u201907\u20331 davanti a Theo Schely e Clement Parisse. Il migliore dei nostri rappresentanti \u00e8 risultato <strong>Martin Coradazzi,<\/strong> dodicesimo, seguito da Michael Abram quattordicesimo, Alessandro Chiocchetti diciottesimo e Elia Barp ventesimo.<\/p>\n<p>In campo femminile terza posizione per Francesca Franchi, battuta dalla svizzera D\u00e9siree Steiner e dalla francese Delphine Claudel, nella top ten anche <strong>Martina Di Centa<\/strong> settima, <strong>Cristina Pittin<\/strong> ottava e Martina Bellini decima.<\/p>\n<p><a href=\"http:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-content\/uploads\/sites\/34\/2022\/11\/classifiche-1.pdf\">CLASSIFICHE<\/a><\/p>\n<p><em><strong>(nella foto Martin Coradazzi)<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In programma una 11.5 km a tecnica classica, presenti atleti di Italia, Francia, Svizzera, Canada e Germania<\/p>\n","protected":false},"author":4,"featured_media":83703,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/91420"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=91420"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/91420\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/83703"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=91420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=91420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=91420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}