{"id":18290,"date":"2014-03-15T13:42:37","date_gmt":"2014-03-15T13:42:37","guid":{"rendered":"http:\/\/www.fisifvg.org\/2014\/03\/15\/153-alpino-finali-coppa-italia-master-gigante-a-rossana-cellini\/"},"modified":"2014-03-15T13:42:37","modified_gmt":"2014-03-15T13:42:37","slug":"153-alpino-finali-coppa-italia-master-gigante-a-rossana-cellini","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2014\/03\/15\/153-alpino-finali-coppa-italia-master-gigante-a-rossana-cellini\/","title":{"rendered":"15\/3- ALPINO: Finali Coppa Italia Master, gigante a Rossana Cellini"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>15-3-2014<\/strong><\/span> Seconda giornata per le <strong>finali di Coppa Italia Master <\/strong>di Pampeago, ancora con gli sciatori FVG protagonisti.<\/p>\n<p>In programma il gigante, che come accaduto ieri nel superG ha visto<strong> Andrea Gaier<\/strong> chiudere terzo assoluto Master A, mentre nella categoria A4 &egrave; giunto secondo. <br \/>Nella classifica assoluta Master B <strong>Alessandro Beltrame <\/strong>si &egrave; piazzato quarto mentre l&#8217;unico successo di categoria &egrave; stato quelli di <strong>Rossana Cellini<\/strong> nelle C4.<\/p>\n<p>Questi i podi di categoria:<\/p>\n<p><span style=\"text-decoration: underline\"><strong>PRIMO POSTO<\/strong><\/span> &#8211; <strong>Rossana Cellini<\/strong> (C4, Sci Club 5 Cime).<br \/><span style=\"text-decoration: underline\"><strong>SECONDO POSTO<\/strong><\/span> &#8211; <strong>Andrea Gaier<\/strong> (A4, Sci Club Monte Canin), <strong>Mariateresa Zilli<\/strong> (C6, Sci Club Feletto).<br \/><span style=\"text-decoration: underline\"><strong>TERZO POSTO<\/strong><\/span> &#8211; <strong>Alessandro Beltrame<\/strong> (B6, Sci CAI XXX Ottobre).<\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto Rossana Cellini<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Podi anche per Andrea Gaier, Mariateresa Zilli e Alessandro Beltrame<\/p>\n","protected":false},"author":4,"featured_media":18291,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/18290"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=18290"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/18290\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/18291"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=18290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=18290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=18290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}