{"id":18278,"date":"2014-03-14T19:44:37","date_gmt":"2014-03-14T19:44:37","guid":{"rendered":"http:\/\/www.fisifvg.org\/2014\/03\/14\/143-fondo-start-list-campionati-provinciali-triestini\/"},"modified":"2014-03-14T19:44:37","modified_gmt":"2014-03-14T19:44:37","slug":"143-fondo-start-list-campionati-provinciali-triestini","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2014\/03\/14\/143-fondo-start-list-campionati-provinciali-triestini\/","title":{"rendered":"14\/3- FONDO: start list Campionati Provinciali Triestini"},"content":{"rendered":"<p><span style=\"color: #ff0000\"><strong><span style=\"text-decoration: underline\">14-3-2014<\/span><\/strong><\/span> Si disputano domani (sabato 15) all'&#8221;Arena Paruzzi&#8221; di <strong>Tarvisio <\/strong>i <strong>Campionati Provinciali Triestini di sci di fondo<\/strong>, organizzati dal <strong>SK Devin.<\/strong><\/p>\n<p>In programma una prova a tecnica classica con partenza in linea per tutte le categorie.<\/p>\n<p>Prime partenze alle 9.30: in allegato la start list.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La gara si svolger\u00e0 domani alla Ski Arena Paruzzi di Tarvisio<\/p>\n","protected":false},"author":4,"featured_media":18279,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/18278"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=18278"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/18278\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/18279"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=18278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=18278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=18278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}