{"id":18232,"date":"2014-03-09T16:16:00","date_gmt":"2014-03-09T16:16:00","guid":{"rendered":"http:\/\/www.fisifvg.org\/2014\/03\/09\/93-alpino-podio-per-kandutsch-e-beltrame-nel-gigante-njr-di-cortina\/"},"modified":"2014-03-09T16:16:00","modified_gmt":"2014-03-09T16:16:00","slug":"93-alpino-podio-per-kandutsch-e-beltrame-nel-gigante-njr-di-cortina","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2014\/03\/09\/93-alpino-podio-per-kandutsch-e-beltrame-nel-gigante-njr-di-cortina\/","title":{"rendered":"9\/3- ALPINO: podio per Kandutsch e Beltrame nel gigante NJR di Cortina"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>9-3-2014<\/strong><\/span> Belle prestazioni per i ragazzi della squadra di Comitato, guidata dal selezionatore <strong>Massimo Lazzaro<\/strong>, nel gigante <strong>FIS NJR <\/strong>di Cortina.<\/p>\n<p><strong>Marco Kandutsch<\/strong> del <em><strong>Bachmann Cultura&amp;Sport<\/strong><\/em> &egrave; giunto secondo assoluto mentre <strong>Andrea Beltrame<\/strong> dello<em><strong> Sci CAI XXX Ottobre <\/strong><\/em>ha conquistato il terzo posto fra gli Aspiranti.<\/p>\n<p>Beltrame ha chiuso ottavo assoluto alle spalle di<strong> Marco Marocco <\/strong>dello <em><strong>Sci Club Pordenone<\/strong><\/em>, autore del miglior tempo nella seconda manche.<\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto Marco Kandutsch (a sinistra) sul podio<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il tarvisiano secondo assoluto, il triestino terzo Aspiranti<\/p>\n","protected":false},"author":4,"featured_media":18233,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/18232"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=18232"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/18232\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/18233"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=18232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=18232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=18232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}