{"id":18126,"date":"2014-03-01T19:37:57","date_gmt":"2014-03-01T19:37:57","guid":{"rendered":"http:\/\/www.fisifvg.org\/2014\/03\/01\/13-fondo-start-list-trofeo-panorama-a-piancavallo\/"},"modified":"2014-03-01T19:37:57","modified_gmt":"2014-03-01T19:37:57","slug":"13-fondo-start-list-trofeo-panorama-a-piancavallo","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2014\/03\/01\/13-fondo-start-list-trofeo-panorama-a-piancavallo\/","title":{"rendered":"1\/3- FONDO: start list &#8220;Trofeo Panorama&#8221; a Piancavallo"},"content":{"rendered":"<p><span style=\"font-family: Tahoma;font-size: x-small\"><span style=\"font-family: Tahoma;font-size: x-small\"><strong><span style=\"text-decoration: underline;color: #ff0000\">1-3-2014<\/span> Domenica 2 marzo<\/strong> a <strong>Piancavallo <\/strong>si disputeranno i <strong>Campionati Regionali lunga distanza a tecnica libera,<\/strong> riservati ai <strong>Seniores,<\/strong> mentre Aspiranti e Juniores saranno impegnati in una gara regionale, sempre a passo pattinato.<\/p>\n<p>Per Superbaby, Baby, Cuccioli e Ragazzi &egrave; in programma una gimkana, ancora in skating.<\/p>\n<p><span style=\"text-decoration: underline;font-size: small\"><strong>IMPORTANTE<\/strong><\/span>: <strong>esclusivamente<\/strong> per la categoria <span style=\"font-size: small\"><strong>Allievi, maschile e femminie<\/strong><\/span>, si disputer&agrave; una <span style=\"text-decoration: underline;font-size: small\"><strong>gimkana sprint.<\/strong><\/span><\/p>\n<p>L&#8217;organizzazione &egrave; curata dallo <strong>Sci Club Panorama<\/strong>, che metter&agrave; in palio il <em><strong>22&deg; Trofeo Panorama.<\/p>\n<p><\/strong><\/em>In allegato le start list.<\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto Mirco Romanin della Monte Coglians, miglior punteggiato al via<\/strong><\/em><\/span><br \/><em><strong><\/strong><\/em><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domani i Regionali lunga distanza e le gimkana per le categorie giovanili<\/p>\n","protected":false},"author":4,"featured_media":18127,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/18126"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=18126"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/18126\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/18127"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=18126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=18126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=18126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}