{"id":18090,"date":"2014-02-26T08:17:43","date_gmt":"2014-02-26T08:17:43","guid":{"rendered":"http:\/\/www.fisifvg.org\/2014\/02\/26\/262-alpino-emanuele-buzzi-sesto-e-undicesimo-ai-mondiali-juniores\/"},"modified":"2014-02-26T08:17:43","modified_gmt":"2014-02-26T08:17:43","slug":"262-alpino-emanuele-buzzi-sesto-e-undicesimo-ai-mondiali-juniores","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2014\/02\/26\/262-alpino-emanuele-buzzi-sesto-e-undicesimo-ai-mondiali-juniores\/","title":{"rendered":"26\/2- ALPINO: Emanuele Buzzi sesto e undicesimo ai Mondiali Juniores"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>26-2-2014<\/strong><\/span> Hanno preso il via a Jasna, in Slovacchia, i&nbsp; <strong>Campionati Mondiali Juniores di sci alpino<\/strong>.<\/p>\n<p>In gara anche il Forestale <strong>Emanuele Buzzi<\/strong>, cresciuto nello <strong>Sci Club Sappada <\/strong>e leader della squadra del <strong>Comitato FISI FVG<\/strong>, impegnato oggi nel supergigante e nella supercombinata.<\/p>\n<p>Ebbene, nel superG Emanuele ha ottenuto un ottimo undicesimo posto (su 125 iscritti) nella gara che ha visto l&#8217;azzurro Matteo De Vettori conquistare il bronzo.<\/p>\n<p>Successivamente si &egrave; migliorato, chiudendo splendido sesto la supercombinata, a mezzo secondo dal vincitore De Vettori e a soli 0&#8243;41 dal podio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Forestale di Sappada protagonista in supercombinata e superG<\/p>\n","protected":false},"author":4,"featured_media":18091,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/18090"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=18090"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/18090\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/18091"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=18090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=18090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=18090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}