{"id":18088,"date":"2014-02-25T18:23:36","date_gmt":"2014-02-25T18:23:36","guid":{"rendered":"http:\/\/www.fisifvg.org\/2014\/02\/25\/252-sci-paralimpico-coppa-del-mondo-tre-podi-per-gli-azzurri\/"},"modified":"2014-02-25T18:23:36","modified_gmt":"2014-02-25T18:23:36","slug":"252-sci-paralimpico-coppa-del-mondo-tre-podi-per-gli-azzurri","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2014\/02\/25\/252-sci-paralimpico-coppa-del-mondo-tre-podi-per-gli-azzurri\/","title":{"rendered":"25\/2- SCI PARALIMPICO: Coppa del Mondo, tre podi per gli azzurri"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>25-2-2014<\/strong><\/span> Splendida giornata oggi a <strong>Tarvisio<\/strong>, sia dal punto di vista climatico che da quello sportivo-agonistico. Sulla pista Di Prampero si sono svolte le due ultime discese libere della stagione 2014 della <strong>IPCAS Coppa del mondo di sci alpino paralimpico.<\/strong><br \/>I migliori 50 atleti internazionali si sono cimentati su un tracciato molto tecnico e veloce dalla lunghezza di 1780 metri e caratterizzato da neve compatta e ben preparata.<\/p>\n<p>Ottimi risultati per la squadra italiana, in previsione dei prossimi Giochi paralimpici invernali di Sochi, in Russia che inizieranno il 7 marzo. Doppio argento per la coppia Alessandro Daldoss e Luca Negrini (la Guida) nella classe Visually Impaired mentre <strong>Melania Corradini <\/strong>dello<strong> Sci Club Due<\/strong>, societ&agrave; organizzatrice della manifestazione, nella categoria Standing, ha conquistato due bronzi nelle rispettive gare.<\/p>\n<p>Nelle discese femminili 2 ori per la russa Aleksandra Frantceva (Guida: Pavel Zabotin) nella Visually Impaired, per la compagna di squadra Inga Medvedeva nella Standing e per l&#8217;austriaca Claudia Loesch nel Sitting.<br \/>In campo maschile doppia vittoria per l&#8217;americano Mark Bathum (guidato da Cade Yamamoto), nella classe Visually Impaired, per l&#8217;austriaco Markus Salcher (Standing) e per il giapponese Akira Kano (Sitting).<\/p>\n<p>Domani, ultima giornata di gare con la Supercombinata (ore 10 SuperG ed ore 13 slalom speciale) ancora sulla pista Artico Di Prampero, che sar&agrave; in diretta live Streaming sempre sul sito ufficiale della manifestazione <a href=\"http:\/\/www.sc2worldcup.com\" target=\"_blank\" rel=\"noopener\"><strong>www.sc2worldcup.com<\/strong><\/a>. Nel pomeriggio si svolgeranno le premiazioni finali con l&#8217;assegnazione anche dei trofei conclusivi della IPCAS Coppa del mondo di sci alpino paralimpico 2014, precedute dalla sfilata delle squadre con la fanfara della Brigata Julia lungo via Roma.<br \/>Il programma prevedeva tale competizione gioved&igrave; 27 febbraio ma &eacute; stata anticipata a mercoled&igrave; viste le previsioni meteo che annunciano un peggioramento in arrivo nella notte del 26.<\/p>\n<p>Info, gallery e video della giornata su <a href=\"http:\/\/www.sc2worldcup.com\" target=\"_blank\" rel=\"noopener\"><strong>www.sc2worldcup.com <\/strong><\/a>e sui social media dell&#8217;organizzazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><b>Oggi a Tarvisio prima giornata per la IPCAS Coppa del Mondo di sci alpino<\/b><\/p>\n","protected":false},"author":4,"featured_media":18089,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/18088"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=18088"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/18088\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/18089"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=18088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=18088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=18088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}