{"id":17995,"date":"2014-02-16T13:55:06","date_gmt":"2014-02-16T13:55:06","guid":{"rendered":"http:\/\/www.fisifvg.org\/2014\/02\/16\/162-alpino-circuito-despar-classifiche-babycuccioli-tarvisio\/"},"modified":"2014-02-16T13:55:06","modified_gmt":"2014-02-16T13:55:06","slug":"162-alpino-circuito-despar-classifiche-babycuccioli-tarvisio","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2014\/02\/16\/162-alpino-circuito-despar-classifiche-babycuccioli-tarvisio\/","title":{"rendered":"16\/2- ALPINO: circuito Despar, classifiche Baby\/Cuccioli Tarvisio"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>16-2-2014<\/strong><\/span> Si &egrave; svolto oggi a <strong>Tarvisio<\/strong> uno slalom<strong> Baby\/Cuccioli <\/strong>del <strong>circuito regionale &#8220;Despar&#8221;<\/strong> organizzato dall&#8217;<strong>Unione Sportiva Camporosso<\/strong>, che ha messo in palio l&#8217;omonimo Trofeo, vinto dallo <strong>Sci Club Pordenone <\/strong>sullo <strong>Sci CAI XXX Ottobre<\/strong> e il <strong>Cimenti Sci Carnia<\/strong>.<\/p>\n<p>Questi i podi.<\/p>\n<p><span style=\"text-decoration: underline\"><strong>BABY 1 FEMMINILE<\/strong><\/span>: 1.<strong> Veronica Del Rosso<\/strong> (XXX Ottobre) 37.50, 2. Margherita Lozza (Fornese) 38.05, 3. Anna Cappellari (Val Pesarina) 38.83.<br \/><span style=\"text-decoration: underline\"><strong>BABY 2 FEMMINILE<\/strong><\/span>: 1. <strong>Sofia Colombo<\/strong> (5 Cime) 29.91, 2. Gaia Vidrigh (Bachmann) 30.73, 3. Elena Frandoli (Aldo Moro) 31.87.<br \/><span style=\"text-decoration: underline\"><strong>BABY 1 MASCHILE<\/strong><\/span>: 1. <strong>Stefano Toscano<\/strong> (Sc Pordenone) 34.44, 2. Matteo Fragiacomo (Sc 70) 34.46, 3. Simone Candotti (Fornese) 35.61.<br \/><span style=\"text-decoration: underline\"><strong>BABY 2 MASCHILE<\/strong><\/span>: 1. <strong>Francesco La Grassa <\/strong>(Sc Pordenone) 30.07, 2. Erik Bordon (Devin) 31.31, 3. Andrea De Nadai (Sc Aviano) 31.88.<br \/><span style=\"text-decoration: underline\"><strong>CUCCIOLI 1 FEMMINILE<\/strong><\/span>: 1. <strong>Caterina Sinigoi<\/strong> (Devin) 33.22, 2. Ginevra Pase (Aviano) 33.67, 3. Anna D&#8217;Andrea (5 Cime) 34.74.<br \/><span style=\"text-decoration: underline\"><strong>CUCCIOLI 2 FEMMINILE<\/strong><\/span>: 1. <strong>Sveva Della Mea <\/strong>(Lussari) 32.67, 2. Jennifer Rosca (Lussari) 33.64, 3. Giulia Lidia Vidrigh (Bachmann) 34.10. <br \/><span style=\"text-decoration: underline\"><strong>CUCCIOLI 1 MASCHILE<\/strong><\/span>: 1. <strong>Alessio Tramontin<\/strong> (Sc Sacile) 33.57, 2. Carlo Palmegiano (Aldo Moro) 34.66, 3. Sebastiano Maddalena (Cimenti) e Alberto Benedetti (Lussari) 34.82.<br \/><span style=\"text-decoration: underline\"><strong>CUCCIOLI 2 MASCHILE<\/strong><\/span>: 1. <strong>Giacomo Vidoni <\/strong>(XXX Ottobre) 32.48, 2. Iacopo Biz (Sc Aviano) 35.10, 3. Simone Coradazzi (Fornese) 35.76.<\/p>\n<p>In considerazione della pioggia insistente, il previsto slalom promozionale non si &egrave; disputato.<\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto il podio Baby 1 maschile<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><b>Oggi il Trofeo US Camporosso organizzato dallo sci club omonimo<\/b><\/p>\n","protected":false},"author":4,"featured_media":17996,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17995"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17995"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17995\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17996"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}