{"id":17975,"date":"2014-02-15T07:39:40","date_gmt":"2014-02-15T07:39:40","guid":{"rendered":"http:\/\/www.fisifvg.org\/2014\/02\/15\/152-olimpiadi-oggi-in-gara-marina-piller-e-sebastian-colloredo\/"},"modified":"2014-02-15T07:39:40","modified_gmt":"2014-02-15T07:39:40","slug":"152-olimpiadi-oggi-in-gara-marina-piller-e-sebastian-colloredo","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2014\/02\/15\/152-olimpiadi-oggi-in-gara-marina-piller-e-sebastian-colloredo\/","title":{"rendered":"15\/2- OLIMPIADI: oggi in gara Marina Piller e Sebastian Colloredo"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>15-2-2014<\/strong><\/span> Alle <strong>Olimpiadi di Sochi <\/strong>oggi stati sono protagonisti due ragazzi cresciuti nel Comitato FISI FVG.<\/p>\n<p><strong>Marina Piller,<\/strong> scuola <em><strong>ASD Camosci,<\/strong><\/em> ha fatto parte del quartetto italiano giunto ottavo nella staffetta 4&#215;5 km femminile di fondo vinto dalla Svezia su Finlandia e Germania.<\/p>\n<p><strong>Sebastian Colloredo<\/strong>, cresciuto nello<strong><em> Sci CAI Monte Lussari<\/em>, <\/strong>&egrave; stato ll&#8217;unico italiano in gara nella finale del salto dal trampolino grande, qualificandosi per la seconda serie e chiudendo al trentesimo posto la gara vinta dal polacco Stoch.<\/p>\n<p>Domani in gara <strong>Giorgio Di Centa <\/strong>nella staffetta 4&#215;10 km maschile di fondo.<\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto Marina Piller<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sappadina ottava nella staffetta, il tarvisiano trentesimo sul trampolino grande<\/p>\n","protected":false},"author":4,"featured_media":17976,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17975"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17975"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17975\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17976"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}