{"id":17961,"date":"2014-02-14T08:44:05","date_gmt":"2014-02-14T08:44:05","guid":{"rendered":"http:\/\/www.fisifvg.org\/2014\/02\/14\/142-alpino-a-meta-marzo-ritornano-i-provinciali-transfrontalieri\/"},"modified":"2014-02-14T08:44:05","modified_gmt":"2014-02-14T08:44:05","slug":"142-alpino-a-meta-marzo-ritornano-i-provinciali-transfrontalieri","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2014\/02\/14\/142-alpino-a-meta-marzo-ritornano-i-provinciali-transfrontalieri\/","title":{"rendered":"14\/2- ALPINO: a met\u00e0 marzo ritornano i Provinciali Transfrontalieri"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>14-2-2014<\/strong><\/span> <strong>Sabato 15 <\/strong>e<strong> domenica 16 marzo<\/strong> le nevi slovene di <strong>Kranjska Gora<\/strong> ospiteranno la decima edizione dei <strong>Campionati Provinciali Transfrontalieri<\/strong>, promossi dal <strong>Comitato Fisi Provinciale di Gorizia<\/strong>.<br \/>Diffidenze iniziali, timori del nuovo, incertezze del futuro, ma anche entusiasmo e voglia di provare, stimoli&nbsp; degli amici, tenacia: il coraggio di allora, credendo nei valori dello sport e dell&rsquo;amicizia, prima ancora dei confini fisici, faceva dimenticare ogni problema e fatica, dando il l&agrave; ad una bellissima manifestazione di sci, sport e amicizia.<br \/>E ora, con rinnovata fiducia ed entusiasmo, la Fisi goriziana proiettia il suo sguardo alle future edizioni, conscia di aver iniziato anni fa un innovativo percorso.<br \/>Come ogni anno a darsi battaglia atleti goriziani al di qua e al di l&agrave; di un confine ormai inesistente, con comune classifica per il titolo di campione transfrontaliero ed estrapolazione dei soli atleti italiani per il titolo&nbsp; di campione provinciale FISI: stesse doppie classifiche per il trofeo a squadre. <br \/>Con entusiasmo hanno aderito al comitato d&rsquo;onore, quest&rsquo;anno, anche la presidente della Regione <strong>Debora Serracchiani <\/strong>ed il presidente del Coni <strong>Giovanni Malag&ograve;<\/strong>, che hanno formulato agli organizzatori l&#8217;augurio per la perfetta riuscita della manifestazione.<\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto i campioni provinciali 2013 Ginevra Gabrielli e Marco Ventin<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La classica manifestazione \u00e8 organizzata dal Comitato FISI di Gorizia<\/p>\n","protected":false},"author":4,"featured_media":17962,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17961"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17961"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17961\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17962"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}