{"id":17957,"date":"2014-02-13T07:08:53","date_gmt":"2014-02-13T07:08:53","guid":{"rendered":"http:\/\/www.fisifvg.org\/2014\/02\/13\/132-olimpiadi-marina-piller-trentunesima-nella-10-km-tc\/"},"modified":"2014-02-13T07:08:53","modified_gmt":"2014-02-13T07:08:53","slug":"132-olimpiadi-marina-piller-trentunesima-nella-10-km-tc","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2014\/02\/13\/132-olimpiadi-marina-piller-trentunesima-nella-10-km-tc\/","title":{"rendered":"13\/2- OLIMPIADI: Marina Piller trentunesima nella 10 km tc"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>13-2-2014<\/strong><\/span> Seconda gara alle <strong>Olimpiadi di Sochi<\/strong> per <strong>Marina Piller.<\/strong><\/p>\n<p>La Forestale di Sappada, cresciuta nell&#8217;<strong>ASD Camosci<\/strong>, ha partecipato oggi alla 10 km a tecnica classica di fondo, chiudendo al 31&deg; posto.<\/p>\n<p>Oro alla polacca Justyna Kowalczyk, argento alla svedese Charlotte Kalla, bronzo alla norvegese Therese Johaug.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Secondo impegno a Sochi per la fondista scuola ASD Camosci. Vince la Kowalczyk<\/p>\n","protected":false},"author":4,"featured_media":17958,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17957"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17957"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17957\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17958"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}