{"id":17891,"date":"2014-02-07T17:48:51","date_gmt":"2014-02-07T17:48:51","guid":{"rendered":"http:\/\/www.fisifvg.org\/2014\/02\/07\/72-start-list-giganti-babycuccioli-e-giovaniseniormaster\/"},"modified":"2014-02-07T17:48:51","modified_gmt":"2014-02-07T17:48:51","slug":"72-start-list-giganti-babycuccioli-e-giovaniseniormaster","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2014\/02\/07\/72-start-list-giganti-babycuccioli-e-giovaniseniormaster\/","title":{"rendered":"7\/2- Start List giganti Baby\/Cuccioli e Giovani\/Senior\/Master"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>7-2-2014<\/strong><\/span> Pubblichiamo l&#8217;ordine di partenza dello dello slalom gigante Giovani\/Seniores\/Master in programma domani a Piancavallo e dello slalom gigante Baby\/Cuccioli, previsto sempre domani a Forni di Sopra<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domani gare a Forni di Sopra e Piancavallo<\/p>\n","protected":false},"author":4,"featured_media":17886,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17891"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17891"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17891\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17886"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}