{"id":17875,"date":"2014-02-06T09:45:27","date_gmt":"2014-02-06T09:45:27","guid":{"rendered":"http:\/\/www.fisifvg.org\/2014\/02\/06\/62-fondo-in-venti-dal-fvg-alla-nazionale-giovanicoppa-italia\/"},"modified":"2014-02-06T09:45:27","modified_gmt":"2014-02-06T09:45:27","slug":"62-fondo-in-venti-dal-fvg-alla-nazionale-giovanicoppa-italia","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2014\/02\/06\/62-fondo-in-venti-dal-fvg-alla-nazionale-giovanicoppa-italia\/","title":{"rendered":"6\/2- FONDO: in venti dal FVG alla Nazionale Giovani+Coppa Italia"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>6-2-2014<\/strong><\/span> I fondisti del Comitato FISI FVG parteciperanno nel fine settimana a Chiusa Pesio (Cuneo) ad una <strong>Nazionale Giovani+Coppa Italia<\/strong>.<\/p>\n<p>Sabato sono in programma le prove Distance a tecnica libera, domenica quelle a passo alternato.<\/p>\n<p>Il coordinatore Aldo Plai ha convocato tutti gli esponenti della squadra di Comitato, ovvero Martina Di Gallo, Francesca Comarella, Kristin Kanduth, Serena Muller, Alice Vegliach, Gilberto Panisi (reduce dai Mondiali Juniores), Nicola Iona, Simone Ferigo, Mattia Preschern, Gianluca Copetti, Matteo Mischkot e Sebastiano Dalle Ave, ai quali si aggiungono Carlo Marchesin e Luca Zanier.<\/p>\n<p>In gara anche sei atleti dell&#8217;ultimo anno Allievi: Cristina Pittin, Veronica Danieli, Asia Patini, Michele Rovere, Cristian Ferigo e Martin Coradazzi.<\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto Veronica Danieli<\/strong><\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fine settimana a Chiusa Pesio con due prove Distance<\/p>\n","protected":false},"author":4,"featured_media":17876,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17875"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17875"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17875\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17876"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}