{"id":17746,"date":"2014-01-21T16:36:26","date_gmt":"2014-01-21T16:36:26","guid":{"rendered":"http:\/\/www.fisifvg.org\/2014\/01\/21\/211-festa-sulla-neve-da-giovedi-a-sabato-con-zoldo-be-a-fan\/"},"modified":"2014-01-21T16:36:26","modified_gmt":"2014-01-21T16:36:26","slug":"211-festa-sulla-neve-da-giovedi-a-sabato-con-zoldo-be-a-fan","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2014\/01\/21\/211-festa-sulla-neve-da-giovedi-a-sabato-con-zoldo-be-a-fan\/","title":{"rendered":"21\/1- Festa sulla neve da gioved\u00ec a sabato con &#8220;Zoldo be a fan&#8221;"},"content":{"rendered":"<p style=\"margin-bottom: 0cm;line-height: 150%;text-align: left\"><span style=\"text-decoration: underline;color: #ff0000\"><strong>21-1-2014<\/strong><\/span> <em><strong>Riceviamo e volentieri pubblichiamo<\/strong><\/em>. <\/p>\n<p><span style=\"font-size: x-small\"><span style=\"font-family: Sky Text,sans-serif\">Le Dolomiti bellunesi vivranno tre giorni di grande festa sulla neve: il <strong>23, 24 e 25 gennaio 2014 <\/strong> a scendere in pista a Palafavera (Zoldo Alto, Belluno) saranno <strong>i valori dello sport e della solidariet&agrave;<\/strong> in occasione di &#8220;<strong>Zoldo Be a Fan<\/strong>&#8220;. <\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;line-height: 150%;text-align: left\"><span style=\"font-size: x-small\"><span style=\"font-family: Sky Text,sans-serif\"><strong>L&rsquo; Associazione sportiva dilettantistica sci di fondo<\/strong> <strong>Val di Zoldo<\/strong> organizza, in collaborazione con <strong>AIPD Belluno e Special Olympics Italia (Regione Veneto) <\/strong> una manifestazione sportiva non agonistica che coinvolger&agrave; sulla neve atleti con disabilit&agrave; intellettiva  a fianco di studenti delle Scuole Primarie e Secondarie della Val di Zoldo, dell&rsquo;istituto Catullo di Belluno indirizzo sociale nonch&eacute; l&rsquo;associazione Dottor Clown di Belluno. <strong><span style=\"background: #ffff00\">Perch&eacute; lo sport unisce<\/span>!<\/strong> <\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;line-height: 150%;text-align: left\"><span style=\"font-size: x-small\"><span style=\"font-family: Sky Text,sans-serif\">Una tre giorni di giochi e divertimento, per avvicinare  alle discipline invernali nuovi atleti e ragazzi diversamente abili. Dalla <strong>camminata con racchette<\/strong> allo <strong>sci di fondo<\/strong> e <strong>sci alpino<\/strong>: le piste di Zoldo Alto alterneranno <strong>momenti ludici<\/strong> e di introduzione allo sport a <strong>momenti di confronto competitivo. <\/strong><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;line-height: 150%;text-align: left\"><span style=\"font-size: x-small\"><span style=\"font-family: Sky Text,sans-serif\">E non solo: non mancheranno incontri formativi  e ludici dove verranno raccontate le esperienze vissute in prima persona da alcuni atleti. <\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;line-height: 150%;text-align: left\"><span style=\"font-size: x-small\"><span style=\"font-family: Sky Text,sans-serif\">Lo straordinario evento vedr&agrave; anche  la partecipazione di speciali ospiti , ad esemipio,  il sabato  25 sulle piste di Palafavera presenzier&agrave; il  <strong>responsabile settore tecnico del Chievo calcio Umberto Perisinotto<\/strong><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;line-height: 150%;text-align: left\"><span style=\"font-size: x-small\"><span style=\"font-family: Sky Text,sans-serif\">Interverr&agrave; anche <strong>la squadra  nazionale di Biathlon al suo completo che sar&agrave; successivamente in ritiro preolimpico presso la nuova struttura di Palafavera.<\/strong> <\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;line-height: 150%\"><span style=\"font-family: Sky Text,sans-serif\"><span style=\"font-size: x-small\"><strong>CONTATTI UTILI E INFORMAZIONI:<\/strong><\/span><\/span><strong><span style=\"font-size: x-small\"><span style=\"font-family: Sky Text,sans-serif\"> Nicola \tMolin Pradel cell 335.283197<\/span><\/span><\/strong><\/p>\n<p style=\"margin-bottom: 0cm;text-align: left\"><strong><em><span style=\"font-family: Sky Text,sans-serif\"><span style=\"color: #ff0000\"><span style=\"color: #000000\">Altri ospiti speciali da confermare:&nbsp;<\/span><span style=\"color: #000000\"><span style=\"text-decoration: underline\">Gabriella Paruzzi<\/span>, <\/span><\/span><\/span><\/em><\/strong><strong><em><span style=\"font-family: Sky Text,sans-serif\"><span style=\"color: #ff0000\"><span style=\"color: #000000\">medaglia d&rsquo;oro alle Olimpiadi di Salt Lake City 2002, e <span style=\"text-decoration: underline\">Karen Putzer<\/span> in partenza  per Sochi 2014, oltre ad <\/span><\/span><\/span><\/em><span style=\"font-family: Sky Text,sans-serif\"><span style=\"color: #ff0000\"><span style=\"color: #000000\">Antonio Ross<\/span><\/span><\/span><em><span style=\"font-family: Sky Text,sans-serif\"><span style=\"color: #ff0000\"><span style=\"color: #000000\">i plurimedagliato Olimpico e ora impegnato in qualit&agrave; di Assessore allo sport alla Regione Lombardia da sempre impegnato in attivit&agrave; di sport solidale.<\/span><\/span><\/span><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La manifestazione si svolge in collaborazione con Special Olympics Italia<\/p>\n","protected":false},"author":4,"featured_media":17747,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17746"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17746"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17746\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17747"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}