{"id":17696,"date":"2014-01-13T16:26:44","date_gmt":"2014-01-13T16:26:44","guid":{"rendered":"http:\/\/www.fisifvg.org\/2014\/01\/13\/131-alpino-supercombinate-fis-solo-peter-fill-batte-emanuele-buzzi\/"},"modified":"2014-01-13T16:26:44","modified_gmt":"2014-01-13T16:26:44","slug":"131-alpino-supercombinate-fis-solo-peter-fill-batte-emanuele-buzzi","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2014\/01\/13\/131-alpino-supercombinate-fis-solo-peter-fill-batte-emanuele-buzzi\/","title":{"rendered":"13\/1- ALPINO: supercombinate FIS, solo Peter Fill batte Emanuele Buzzi"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>13-1-2014<\/strong><\/span> Grandissima giornata quella odierna per <strong>Emanuele Buzzi<\/strong>, il diciannovenne Forestale di Sappada leader della <strong>squadra di Comitato FVG<\/strong>.<\/p>\n<p>Oggi ha conquistato il secondo posto in entrambe le <strong>supercombinate FIS<\/strong> disputate a Pila sempre alle spalle di <strong>Peter Fill,<\/strong> ottenendo grandi punteggi, 13.11 e 15.59, rispettivamente il migliore ed il terzo della sua carriera.<\/p>\n<p>Il risultato assume ancora maggior rilevanza perch&egrave; il talento cresciuto nello<strong> Sci Club Sappada <\/strong>ha preceduto nomi come Pangrazzi, Casse, Klotz, Varettoni e Paris.<\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto Buzzi sul podio accanto a Fill<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pila due splendidi secondi posti per il Forestale della squadra FVG<\/p>\n","protected":false},"author":4,"featured_media":17697,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17696"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17696"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17696\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17697"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}