{"id":17672,"date":"2014-01-11T07:53:34","date_gmt":"2014-01-11T07:53:34","guid":{"rendered":"http:\/\/www.fisifvg.org\/2014\/01\/11\/111-club-tadei-pivk-vince-la-sci-alpinistica-in-notturna-di-sappada\/"},"modified":"2014-01-11T07:53:34","modified_gmt":"2014-01-11T07:53:34","slug":"111-club-tadei-pivk-vince-la-sci-alpinistica-in-notturna-di-sappada","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2014\/01\/11\/111-club-tadei-pivk-vince-la-sci-alpinistica-in-notturna-di-sappada\/","title":{"rendered":"11\/1- CLUB: Tadei Pivk vince la Sci alpinistica in notturna di Sappada"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>11-1-2014<\/strong><\/span> <em><strong>Riceviamo e volentieri pubblichiamo<\/strong><\/em>.<\/p>\n<p><strong>Tadei Pivk <\/strong>dell&#8217;<em><strong>Us Aldo Moro<\/strong><\/em> e <strong>Cecilia De Filippo<\/strong> della Dolomiti Ski Alp sono stati i vincitori assoluti del &#8220;<em><strong>9&deg; Trofeo Lorenzo e Mario<\/strong><\/em>&#8220;, la sci alpinistica in notturna organizzata a <strong>Sappada <\/strong>dall&#8217;<strong>ASD Camosci<\/strong>. <\/p>\n<p>Podi anche per altri due esponenti della FISI FVG: 2&deg; fra i maschi<strong> Marco Del Missier <\/strong>della <strong>Societ&agrave; Sportiva Fornese<\/strong>, terza in campo femminile <strong>Lucia Boschetti<\/strong> dell&#8217;Aldo Moro.<\/p>\n<p>La gara sulle ciaspole &egrave; stata vinta da<strong> Raffaele Facchini <\/strong>e<strong> Susanna Di Giorgio<\/strong>.<\/p>\n<p>Ricordiamo che la <strong>prima prova del circuito FISI FVG di sci alpinismo<\/strong> sar&agrave; la &#8220;<em><strong>Vertical Race Ravascletto-Monte Zoncolan<\/strong><\/em>&#8220;, organizzata dall&#8217;<strong>US Aldo Moro<\/strong> ed in programma <strong>sabato 25 gennaio<\/strong>. <\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto Tadei Pivk<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il tarvisiano vince il &#8220;Trofeo Lorenzo e Mario&#8221; organizzato dall&#8217;ASD Camosci<\/p>\n","protected":false},"author":4,"featured_media":17673,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17672"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17672"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17672\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17673"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}