{"id":17640,"date":"2014-01-03T11:58:11","date_gmt":"2014-01-03T11:58:11","guid":{"rendered":"http:\/\/www.fisifvg.org\/2014\/01\/03\/31-alpino-easy-fun-ski-tappa-piancavallo-rinviata-ad-inizio-marzo\/"},"modified":"2014-01-03T11:58:11","modified_gmt":"2014-01-03T11:58:11","slug":"31-alpino-easy-fun-ski-tappa-piancavallo-rinviata-ad-inizio-marzo","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2014\/01\/03\/31-alpino-easy-fun-ski-tappa-piancavallo-rinviata-ad-inizio-marzo\/","title":{"rendered":"3\/1- ALPINO: Easy Fun Ski, tappa Piancavallo rinviata ad inizio marzo"},"content":{"rendered":"<p class=\"MsoNormal\"><span style=\"text-decoration: underline;color: #ff0000\"><strong>3-1-2014<\/strong><\/span> A cause delle avverse condizioni meteo previste per il fine settimana,  lo staff dello Sci Club Pordenone ha deciso di rinviare la tappa di Piancavallo dell'&#8221;Easy Fun Ski&#8221;  del 5\/6 gennaio al<strong> 1&deg; e 2 marzo<\/strong>.<\/p>\n<p class=\"MsoNormal\">Resta inteso che &egrave; confermata la &nbsp;tappa di Folgaria del 11 e  12 gennaio e, a seguire, il 25 e 26 gennaio la tappa in Sicilia  sull&rsquo;Etna.<\/p>\n<p class=\"MsoNormal\">Lo Sci Club Pordenone ringrazia la stazione di Piancavallo  per quanto fin qui fatto.<\/p>\n<p class=\"MsoNormal\">Chi fosse interessato ad ulteriori informazioni p&ugrave;o  consultare il sito <a title=\"blocked::http:\/\/www.easyfunski.com\/\" href=\"http:\/\/www.easyfunski.com\">www.easyfunski.com.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><b>Lo Sci Club Pordenone comunica la variazione causa maltempo<\/b><\/p>\n","protected":false},"author":4,"featured_media":17641,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17640"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17640"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17640\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17641"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}