{"id":17630,"date":"2013-12-30T23:14:09","date_gmt":"2013-12-30T23:14:09","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/12\/30\/3012-alpino-arianna-stocco-nona-nello-slalom-degli-italiani-assoluti\/"},"modified":"2013-12-30T23:14:09","modified_gmt":"2013-12-30T23:14:09","slug":"3012-alpino-arianna-stocco-nona-nello-slalom-degli-italiani-assoluti","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/12\/30\/3012-alpino-arianna-stocco-nona-nello-slalom-degli-italiani-assoluti\/","title":{"rendered":"30\/12- ALPINO: Arianna Stocco nona nello slalom degli Italiani Assoluti"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>30-12-2013<\/strong><\/span> Splendido nono posto per <strong>Arianna Stocco<\/strong> nello slalom dei <strong>Campionati Italiani Assoluti<\/strong> di Bormio.<\/p>\n<p>La diciassettenne dello<strong> Sci Cai Monte Lussar<\/strong>i, esponente della <strong>squadra regionale <\/strong>e studentessa al <strong>liceo Bachmann di Tarvisio,<\/strong> &egrave; stata bravissima in una gara molto dura, che ha visto uscire 50 delle 74 al via.<\/p>\n<p>La gara era open, aperta quindi anche alle straniere, e Arianna al termine della prima manche era trentesima, cos&igrave; &egrave; stata la prima a prendere il via nella seconda.<\/p>\n<p>Alla fine &egrave; risultata la ventesima assoluta, nona delle italiane. Successo per Chiara Costazza su Sarah Pardeller e Marta Benzoni.<\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto Arianna Stocco alla partenza della seconda manche nelle immagini di Raisport<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Splendida prestazione per la lussarina a Bormio<\/p>\n","protected":false},"author":4,"featured_media":17631,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17630"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17630"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17630\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17631"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}