{"id":17620,"date":"2013-12-29T08:32:20","date_gmt":"2013-12-29T08:32:20","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/12\/29\/2912-alpino-da-piancavallo-il-via-al-1-easy-fun-ski\/"},"modified":"2013-12-29T08:32:20","modified_gmt":"2013-12-29T08:32:20","slug":"2912-alpino-da-piancavallo-il-via-al-1-easy-fun-ski","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/12\/29\/2912-alpino-da-piancavallo-il-via-al-1-easy-fun-ski\/","title":{"rendered":"29\/12- ALPINO: da Piancavallo il via al 1\u00b0 &#8220;Easy Fun Ski&#8221;"},"content":{"rendered":"<p style=\"text-align: left\"><span style=\"font-size: small\"><span style=\"text-decoration: underline;color: #ff0000\"><strong>29-12-2013<\/strong><\/span> Parte nel prossimo fine settimana da <strong>Piancavallo<\/strong> &#8220;<em><strong>Easy Fun Ski<\/strong><\/em>&#8220;, il primo circuito  promozionale nazionale dello sci alpino <span style=\"text-decoration: underline\"><strong>non agonistico<\/strong><\/span>, ideato e organizzato dallo <strong>Sci Club Pordenone<\/strong>.<br \/>Questa iniziativa non sostituisce o si sovrappone a  nulla di quanto gi&agrave; esiste ed &egrave; per questo che &egrave; stata denominata dallo Sci Club  Pordenone &#8220;l&#8217;Anello Mancante&#8221;. <br \/>&#8220;Easy Fun Ski&#8221; &egrave; un circuito nazionale nato per far provare ai bambini e ragazzi la splendida sensazione di  un facile agonismo nella speranza che qualcuno di questi si appassioni e faccia  il passo verso l&rsquo;agonismo vero.<br \/>La promozione &egrave; di rigore, ovvero provare i percorsi di  alleanamento in piena sicurezza ed assistiti. Con &#8220;Easy Fun Ski&#8221; i non agonisti potranno finalmente  provare i percorsi di allenamento tra i paletti e al pomeriggio partecipare alla  gara. Durante le prove di riscaldamento gli iscritti saranno  seguiti dallo staff tecnico messo a disposizione dall&rsquo;organizzazione e poi, in  piena sicurezza, potranno partecipare alla gara, che vedr&agrave; protagonisti anche genitori, i tecnici maestri e gli allenatori, visto il contesto di festa della gara ed i  ricchi premi in palio.<br \/>Divertimento quindi assicurato non solo per i piccini,  che al termine della gara potranno intrattenersi con l&rsquo;animazione del team &#8220;Easy  Fun Ski&#8221;, ma anche per i grandi e per le famiglie.<br \/> Ognuna delle 10 tappe sviluppa un evento in due giornate di  gara, sabato e di domenica. Chi vuole potr&agrave; partecipare anche a tutte  e due le giornate. La quota di partecipazione per l&#8217;intera giornata &egrave; di 15 euro ed include<span style=\"font-family: Symbol\"><strong><span style=\"font-family: 'Times New Roman';font-style: normal;font-variant: normal;line-height: normal\"> <\/span><\/strong><\/span><strong>iscrizione all&rsquo;allenamento  tra i paletti con l&rsquo;assistenza di tecnici qualificati,&nbsp;<span style=\"font-family: Symbol\"><span style=\"font-family: 'Times New Roman';font-style: normal;font-variant: normal;line-height: normal\"> <\/span><\/span>tassa d&rsquo;iscrizione alla  gara, <\/strong><strong>zainetto ricco di  premi e<span style=\"font-family: Symbol\"><span style=\"font-family: 'Times New Roman';font-style: normal;font-variant: normal;line-height: normal\"> <\/span><\/span>pettorale  ricordo.<\/strong><\/span><br \/><span style=\"font-size: small\">I migliori tre classificati per ogni gara potranno  accedere alla finale prevista a Santa Caterina sabato 5 Aprile  2014. <br \/>Alla manifestazione possono partecipare <strong>solo i tesserati  Fisi<\/strong> ed &egrave; per questo che all&rsquo;atto dell&rsquo;iscrizione gara <strong>sar&agrave; possibile affiliarsi  alla Fisi direttamente sul campo gara on line<\/strong>. <br \/>Per questo progetto che coinvolge molti poli turistici, lo Sci Club Pordenone ha ottenuto dalla Fisi il patrocinio e l&rsquo;utilizzo del  marchio. Nell&rsquo;organizzazione delle varie tappe, lo Sci Club  Pordenone ha stretto gemellaggi ovunque e in ogni stazione, tanto che l&rsquo;evento sar&agrave;  co-organizzato con il club locale. <br \/>Partner ufficiale di &#8220;Easy Fun Ski&#8221; &egrave; il Ricola Winter  Tour; in questo modo tutti i presenti potranno assaggiare e degustare i prodotti della nota  azienda dolciaria. Responsabile Tecnico del Progetto &egrave; <strong>Luigi Porracin<\/strong> (STF  III&deg; Livello), responsabile di pista <strong>Raniero Mellina<\/strong> (STF II&deg; Liv) alla  Segreteria <strong>Maria Gasparet<\/strong>, referente con la Fisi Milano <strong>Valentino Santarossa <\/strong> (presidente dello sci club) e responsabile Villaggio e promozione il  vicepresidente<strong> Roberto Ongaro. <\/strong><br \/>Queste le 10 tappe, disseminate in tutta Italia: <\/p>\n<p><strong>5\/6 gennaio Piancavallo (PN)<\/strong><br \/><em>11\/12 gennaio Folgaria (TN)<\/em><br \/><em> 25\/26 gennaio Etna (CT)<\/em><br \/> <em>8\/9 febbraio Corno alle Scale (BO)<br \/>15\/16 febbraio Madesimo (SO)<br \/>22\/23 febbraio Bardonecchia (TO)<br \/>15\/16 marzo Andalo (TN)<br \/>22\/23 marzo La Thuile (AO)<br \/>29\/30 marzo Zoldo (BL)<br \/><\/em><em>5 aprile Finalissima Santa Caterina Valfurva  (SO)<\/em><\/p>\n<p>Visto la bont&agrave; dell&rsquo;iniziativa, lo Sci Club Pordenone sta  gi&agrave; pensando alla grande e per la prossima stagione potrebbero esserci tappe di  &#8220;Easy Fun Ski&#8221; anche in Slovenia, Austria, Francia e  Svizzera.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><b>Il circuito promozionale nazionale \u00e8 organizzato dallo Sci Club Pordenone<\/b><\/p>\n","protected":false},"author":4,"featured_media":17621,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17620"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17620"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17620\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17621"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}