{"id":17565,"date":"2013-12-15T14:40:29","date_gmt":"2013-12-15T14:40:29","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/12\/15\/1512-salto-federico-cecon-dodicesimo-in-alpen-cup-a-seefeld\/"},"modified":"2013-12-15T14:40:29","modified_gmt":"2013-12-15T14:40:29","slug":"1512-salto-federico-cecon-dodicesimo-in-alpen-cup-a-seefeld","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/12\/15\/1512-salto-federico-cecon-dodicesimo-in-alpen-cup-a-seefeld\/","title":{"rendered":"15\/12- SALTO: Federico Cecon dodicesimo in Alpen Cup a Seefeld"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>15-12-2013<\/strong><\/span> Miglior prestazione di sempre in <strong>Alpen Cup <\/strong>per <strong>Federico Cecon<\/strong>, impegnato ieri sull&#8217;HS109 di Seefeld, in Austria.<\/p>\n<p>Il lussarino ha ottenuto la dodicesima posizione dopo che al termine del primo salto era addirittura quarto.<br \/>Quarantaduesimo il compagno di club <strong>Zeno Di Lenardo<\/strong>, ieri undicesimo.<\/p>\n<p>Sempre a Seefeld si &egrave; svolta anche la tappa di <strong>combinata nordica<\/strong>, con <strong>Raffaele Buzzi <\/strong>che ha chiuso ventesimo.<\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto Federico Cecon<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miglior risultato di sempre nella manifestazione per il lussarino<\/p>\n","protected":false},"author":4,"featured_media":17566,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17565"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17565"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17565\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17566"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}