{"id":17543,"date":"2013-12-12T09:49:56","date_gmt":"2013-12-12T09:49:56","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/12\/12\/1212-club-presentata-la-nuova-stagione-dello-sk-devin\/"},"modified":"2013-12-12T09:49:56","modified_gmt":"2013-12-12T09:49:56","slug":"1212-club-presentata-la-nuova-stagione-dello-sk-devin","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/12\/12\/1212-club-presentata-la-nuova-stagione-dello-sk-devin\/","title":{"rendered":"12\/12- CLUB: presentata la nuova stagione dello SK Devin"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>12-12-2013<\/strong><\/span> <span style=\"color: #000000\"><em><strong>Riceviamo e volentieri pubblichiamo<\/strong><\/em><\/span>.<\/p>\n<p>Luned&igrave; scorso lo <strong>SK Devin<\/strong> ha presentato l&#8217;attivit&agrave; della nuova stagione invernale alla Casa della Pietra di Aurisina in occasione di un incontro al quale ha collaborato il Comune di Duino Aurisina nell&rsquo;ambito della rassegna &ldquo;Natale con noi&rdquo;. <\/p>\n<p>&ldquo;L&rsquo;anno 2014 sar&agrave;&nbsp; l&rsquo;anno del 40&deg; anno della fondazione di questa associazione&rdquo;, ha sottolineato il presidente <strong>Dario Stolfa.<\/strong> <\/p>\n<p>Tanti gli appuntamenti che vedranno il Devin protagonista: da una gara del circuito regionale Baby\/Cuccioli al &ldquo;Kekec sugli sci&rdquo;, dalla Coppa dell&rsquo;Amicizia delle tre regioni ai Campionati Provinciali Triestini.<\/p>\n<p>Durante la serata sono state presentate le squadre dei Baby-Cuccioli, Ragazzi-Allievi, Giovani-Master, il gruppo Fanjski e i corsi di sci e snowboard, alla presenza degli allenatori e dei responsabili dei vari gruppi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel 2014 verr\u00e0 festeggiato il quarantennale del sodalizio di Duino Aurisina <\/p>\n","protected":false},"author":4,"featured_media":17544,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17543"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17543"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17543\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17544"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}