{"id":17533,"date":"2013-12-08T11:31:23","date_gmt":"2013-12-08T11:31:23","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/12\/08\/812-fondo-bene-la-squadra-regionale-nella-coppa-italia-di-dobbiaco\/"},"modified":"2013-12-08T11:31:23","modified_gmt":"2013-12-08T11:31:23","slug":"812-fondo-bene-la-squadra-regionale-nella-coppa-italia-di-dobbiaco","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/12\/08\/812-fondo-bene-la-squadra-regionale-nella-coppa-italia-di-dobbiaco\/","title":{"rendered":"8\/12- FONDO: bene la squadra regionale nella Coppa Italia di Dobbiaco"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>8-12-2013<\/strong><\/span> Prestazioni decisamente positive per i fondisti FVG nella prova Distance a tecnica libera di <strong>Coppa Italia <\/strong>disputata oggi a Dobbiaco.<\/p>\n<p>Nella 5 km Juniores <strong>Francesca Comarella<\/strong> (Camosci) &egrave; giunta quarta nella gara vinta da Alice Canclini; quindicesima la compagna di squadra <strong>Martina Di Gallo<\/strong>.<\/p>\n<p>Nella 5 km Aspiranti ottava <strong>Kristin Kanduth<\/strong> (Gs 2002), quattordicesima <strong>Alice Vegliach<\/strong> (Sc 70), quindicesima <strong>Serena Muller<\/strong> (Lussari). Vittoria della veneta Anna Comarella, sorella di Francesca.<\/p>\n<p>Nella 10 km Juniores maschile, sesto <strong>Gilberto Panisi <\/strong>(Lussari), tredicesimo <strong>Simone Ferigo<\/strong> (Timaucleulis), diciannovesimo <strong>Mattia Preschern<\/strong> (Gs 2002), ventiduesimo <strong>Nicola Iona <\/strong>(Sc 70). Successo di Sebastiano Pellegrin.<\/p>\n<p>Nella 7.5 km Aspiranti maschile, vinta da Mikael Abram, dodicesimo <strong>Gianluca Copetti <\/strong>(Gs 2002), ventiseiesimo <strong>Sebastiano Dalle Ave<\/strong> (Bachmanni).<\/p>\n<p>&#8220;Siamo molto soddisfatti dei risultati complessivamente ottenuti in questo weekend &#8211; dice il coordinatore regionale <strong>Aldo Plai<\/strong> -. Il lavoro svolto nei mesi scorsi dai tecnici e dai ragazzi sta gi&agrave; dando i primi frutti&#8221;. <\/p>\n<p>Da segnalare inoltre l&#8217;ottimo quarto posto nella 15 km Seniores maschile del tarvisiano <strong>Claudio Muller<\/strong>, giunto a soli 3&#8243;9 dal vincitore Paolo Fanton e a pochi decimi dal terzo, Valerio Checchi.<br \/>Nella 10 km Seniores femminile vinta da Elisa Brocard su Sara Pellegrini, terza <strong>Marina Piller.<\/strong><\/p>\n<p>Le classifiche complete su <a href=\"http:\/\/www.cronomerano.it.\" target=\"_blank\" rel=\"noopener\"><strong>www.cronomerano.it.<\/strong><\/a><\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto Francesca Comarella con il premio per il quarto posto<br \/><\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tanti piazzamenti a ridosso del podio per i fondisti del Comitato FVG<\/p>\n","protected":false},"author":4,"featured_media":17534,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17533"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17533"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17533\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17534"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}