{"id":17482,"date":"2013-11-27T14:12:50","date_gmt":"2013-11-27T14:12:50","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/11\/27\/2711-aprono-nel-week-end-i-poli-di-zoncolan-e-piancavallo\/"},"modified":"2013-11-27T14:12:50","modified_gmt":"2013-11-27T14:12:50","slug":"2711-aprono-nel-week-end-i-poli-di-zoncolan-e-piancavallo","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/11\/27\/2711-aprono-nel-week-end-i-poli-di-zoncolan-e-piancavallo\/","title":{"rendered":"27\/11- Aprono nel week-end i poli di Zoncolan e Piancavallo"},"content":{"rendered":"<p><!--[if gte mso 9]&gt;  Normal 0 14   false false false        MicrosoftInternetExplorer4  &lt;![endif]--><\/p>\n<p><!--[if gte mso 9]&gt;   &lt;![endif]--><!--[if gte mso 10]&gt;--><\/p>\n<p> \/* Style Definitions *\/<br \/>\n table.MsoNormalTable<br \/>\n\t{mso-style-name:&#8221;Tabella normale&#8221;;<br \/>\n\tmso-tstyle-rowband-size:0;<br \/>\n\tmso-tstyle-colband-size:0;<br \/>\n\tmso-style-noshow:yes;<br \/>\n\tmso-style-parent:&#8221;&#8221;;<br \/>\n\tmso-padding-alt:0cm 5.4pt 0cm 5.4pt;<br \/>\n\tmso-para-margin:0cm;<br \/>\n\tmso-para-margin-bottom:.0001pt;<br \/>\n\tmso-pagination:widow-orphan;<br \/>\n\tfont-size:10.0pt;<br \/>\n\tfont-family:&#8221;Times New Roman&#8221;;<br \/>\n\tmso-ansi-language:#0400;<br \/>\n\tmso-fareast-language:#0400;<br \/>\n\tmso-bidi-language:#0400;}<\/p>\n<p class=\"MsoNormal\" style=\"text-align: left\"><span style=\"text-decoration: underline;color: #ff0000\"><strong>27-11-2013<\/strong><\/span> <span style=\"font-size: 11.0pt\">La stagione invernale anticipa l&rsquo;avvio, grazie alle favorevoli condizioni ambientali ed all&rsquo;efficace lavoro dei tecnici Promotur. <br \/><\/span><span style=\"font-size: 11.0pt\">La stagione sciistica si aprir&agrave; nei poli dello Zoncolan e del Piancavallo prima del previsto, nel week-end di <strong>sabato 30 novembre e domenica 1 novembre,<\/strong> con le seguenti possibilit&agrave;:&nbsp;&nbsp; <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: left\"><strong><em><span style=\"text-decoration: underline\"><span style=\"font-size: 11.0pt\">ZONCOLAN<\/span><\/span><span style=\"font-size: 11.0pt\">.<\/span><\/em><\/strong><span style=\"font-size: 11.0pt\"> Si potr&agrave; accedere alle aree sciabili esclusivamente da Sutrio. Saranno disponibili le piste Zoncolan 2 e 4, la parte bassa della pista Zoncolan 3 (area Cuel d&rsquo;Ajar) ed i campetti Cjalcenal. <br \/>Anche gli amanti dello sci nordico potranno contare sull&rsquo;apertura dell&rsquo;anello di fondo. <br \/>Il prezzo dello skipass in giornata sar&agrave; con tariffa ridotta.<br \/>Orario di apertura del polo: 8.30 &ndash; 16.00. <\/p>\n<p><\/span><strong><em><span style=\"text-decoration: underline\"><span style=\"font-size: 11.0pt\">PIANCAVALLO.<\/span><\/span><\/em><\/strong><span style=\"font-size: 11.0pt\"> <span>&nbsp;<\/span>L&rsquo;area sciabile disponibile &egrave; quella della piste Nazionale, Busa Grande, Tublat, Sole e il campo scuola Genzianella. Gli impianti aperti saranno le seggiovie quadriposto Tremol 1, Busa Grande, Tremol II, la seggiovia triposto Sole ed il tappeto Genzianella. Confermata anche l&rsquo;apertura di tutta l&rsquo;area dello sci di fondo. <br \/><\/span><span style=\"font-size: 11.0pt\">I<\/span><span style=\"font-size: 11.0pt\">l prezzo dello skipass in giornata sar&agrave; con tariffa ridotta. <br \/>Orario di apertura del polo: 8.30 &ndash; 16.00. <\/p>\n<p>Il programma &#8220;apertura impianti&#8221; &egrave; indicativo e suscettibile di variazioni, essendo l&rsquo;apertura giornaliera degli impianti condizionata da fatti ed eventi di natura meteorologica. Per verificare le aperture del week-end consultate il sito <\/span><a href=\"http:\/\/www.promotur.org\/\"><span style=\"font-size: 11.0pt\">www.promotur.org<\/span><\/a><span style=\"font-size: 11.0pt\"> alla voce &#8220;Infoneve&#8221;, aggiornata in tempo reale. <\/p>\n<p> <\/span><strong><span style=\"font-size: 11.0pt\">Prevendita pi&ugrave; lunga nei poli Promotur<\/span><\/strong><span style=\"font-size: 11.0pt\"> <\/span><br \/><span style=\"font-size: 11.0pt\">La Direzione dell&rsquo;Agenzia regionale, visto la positiva risposta del mercato e la contestuale anticipazione della apertura della stagione sciistica, ha deciso di prolungare nei Poli la prevendita <strong>sino al 6 dicembre&nbsp;<\/strong><span><\/span>per consentire alle famiglie ed agli Sci Club di acquistare comunque gli skipass stagionali a prezzi vantaggiosi, anche con impianti aperti. <br \/>Pertanto da sabato 30 novembre la prevendita proseguir&agrave; presso le casse dei <strong>poli sciistici<\/strong><strong><\/strong> di Piancavallo, Forni di Sopra, Ravascletto, Sella Nevea e Tarvisio, tutti i giorni in orario 9-12.30 e 14-17. <br \/><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: left\"><span style=\"font-size: 11.0pt\">Gli uffici della sede di Tavagnacco cesseranno la prevendita venerd&igrave; 29 novembre. come da programma iniziale.&nbsp;<\/span><span style=\"font-size: 11.0pt\"><\/span><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p><b>Promotur comunica l&#8217;anticipo dell&#8217;avvio grazie alla favorevoli condizioni meteo<\/b><\/p>\n","protected":false},"author":4,"featured_media":17483,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17482"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17482"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17482\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17483"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}