{"id":17460,"date":"2013-11-21T09:44:17","date_gmt":"2013-11-21T09:44:17","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/11\/21\/2111-riconoscimento-fisi-per-il-centro-di-sci-nordico-di-forni-avoltri\/"},"modified":"2013-11-21T09:44:17","modified_gmt":"2013-11-21T09:44:17","slug":"2111-riconoscimento-fisi-per-il-centro-di-sci-nordico-di-forni-avoltri","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/11\/21\/2111-riconoscimento-fisi-per-il-centro-di-sci-nordico-di-forni-avoltri\/","title":{"rendered":"21\/11- Riconoscimento FISI per il Centro di sci nordico di Forni Avoltri"},"content":{"rendered":"<p style=\"text-align: left\"><span style=\"text-decoration: underline;color: #ff0000\"><strong>21-11-2013<\/strong><\/span> Il <strong>Centro di sci nordico<\/strong> di Piani di Luzza a <strong>Forni Avoltri<\/strong> diventa  <strong>Centro federale riconosciuto dalla Fisi<\/strong>, la Federazione italiana sport  invernali. <br \/>A comunicare la notizia il presidente nazionale <strong>Flavio Roda<\/strong> che in un lettera si &egrave; rivolto poi ai vertici della Regione FVG e al  Coni affinch&egrave; convergano in un fattivo sostegno, anche finanziario, alla  valorizzazione del polo. <br \/>Il complesso, costruito tra il 1990 e il 1992,  grazie alla lungimiranza degli amministratori del tempo e sulla scorta  dei risultati sportivi ottenuti dagli atleti fornesi dello sci nordico,  sia a livello nazionale che internazionali, uno su tutti <strong>Ren&egrave;  Catarinussi<\/strong>, ha visto poi negli anni conquistarsi l&#8217;apprezzamento delle  varie federazioni europee e mondiali, che lo hanno scelto per disputarvi  tantissimi eventi, come i Mondiali Juniores di Biathlon del 1997 o le  Universiadi del 2003.<br \/> &laquo;Siamo davvero soddisfatti per questo  riconoscimento &#8211; commenta il sindaco di Forni Avoltri, nonch&eacute; presidente  della Fisi FVG <strong>Manuele Ferrari <\/strong>&#8211; perch&eacute;  ci&ograve; comporter&agrave; sicuramente un  incremento del suo utilizzo, sia a livello di manifestazioni, sia per i  ritiri delle varie nazionali. E questo si potr&agrave; tradurre inoltre in un  valore aggiunto per l&#8217;economia della val Degano ed anche dei vicini di  Sappada&raquo;. <br \/>La polivalenza dell&#8217;impianto, costituito da un anello di 4 km,  oltre ad una struttura ricettiva e una foresteria, d&agrave; garanzie di  fruizione per tutto l&#8217;arco dell&#8217;anno: d&#8217;inverno infatti c&#8217;&egrave; la  possibilit&agrave; di praticare il biathlon, lo sci di fondo, lo ski arc, ma  anche &egrave; un ideale punto di partenza per le scialpinistiche e le  escursioni con le ciaspe; d&#8217;estate invece si presta allo skiroll, la  corsa, la bicicletta, l&#8217;orienteering, il tiro con l&#8217;arco, ed anche,  nelle vicinanze, l&#8217;equitazione. <br \/>&laquo;Dopo Anterselva in Alto Adige, il  nostro impianto &egrave; il secondo in Italia per importanza &#8211; prosegue Ferrari  &#8211; e pu&ograve; vantare anche un&#8217;ampia ricettivit&agrave;, garantita dal vicino  Villaggio Getur da 800 posti letto oltre che l&#8217;integrabilit&agrave; con le  piste da sci di Cima Sappada. Il  successo ottenuto &egrave; da condividere anche con gli sci club <strong>Monte Coglians <\/strong>e<strong> Cai  Trieste<\/strong> che da sempre stanno lavorando assieme a tanti volontari per il  migliore utilizzo e promozione del centro; d&#8217;ora in poi avremo un  ulteriore elemento di forza per le nostre attivit&agrave;&raquo;. <\/p>\n<p>di <span style=\"color: #800000\"><strong>David Zanirato<\/strong><\/span>, da <a href=\"http:\/\/www.ilgazzettino.it\/\" target=\"_blank\" rel=\"noopener\"><strong>Il Gazzettino<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il presidente Flavio Roda ha scritto una lettera ai vertici della Regione FVG<\/p>\n","protected":false},"author":4,"featured_media":17461,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17460"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17460"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17460\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17461"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}