{"id":17448,"date":"2013-11-14T10:44:58","date_gmt":"2013-11-14T10:44:58","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/11\/14\/1411-cristina-clapiz-nuovo-delegato-tecnico-fis\/"},"modified":"2013-11-14T10:44:58","modified_gmt":"2013-11-14T10:44:58","slug":"1411-cristina-clapiz-nuovo-delegato-tecnico-fis","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/11\/14\/1411-cristina-clapiz-nuovo-delegato-tecnico-fis\/","title":{"rendered":"14\/11- Cristina Clapiz nuovo delegato tecnico FIS"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>14-11-2013<\/strong><\/span> Nello scorso fine settimana si &egrave; tenuta a Modena la riunione annuale di aggiornamento dei<strong> Delegati Tecnici FIS Italiani<\/strong>.<\/p>\n<p>Nel corso della stessa <strong>Cristina Clapiz <\/strong>ha ricevuto il tesserino da Delegato Tecnico, consegnatole dal responsabile nazionale Markus Malsiner.<\/p>\n<p>A Cristina Clapiz sono andati i complimenti della <em><strong>Commissione Giudici di Gara del Friuli Venezia Giulia<\/strong><\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il tesserino le \u00e8 stato consegnato lo scorso week-end a Modena<\/p>\n","protected":false},"author":4,"featured_media":17449,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17448"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17448"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17448\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17449"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}