{"id":17446,"date":"2013-11-13T10:06:31","date_gmt":"2013-11-13T10:06:31","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/11\/13\/1311-fondo-annullato-il-raduno-ragazziallievi-di-domenica-17\/"},"modified":"2013-11-13T10:06:31","modified_gmt":"2013-11-13T10:06:31","slug":"1311-fondo-annullato-il-raduno-ragazziallievi-di-domenica-17","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/11\/13\/1311-fondo-annullato-il-raduno-ragazziallievi-di-domenica-17\/","title":{"rendered":"13\/11- FONDO: annullato il raduno Ragazzi\/Allievi di domenica 17"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>13-11-2013<\/strong><\/span> <strong>Aldo Plai<\/strong>, coordinatore dello sci di fondo del Comitato FISI FVG, comunica che per motivi tecnici il<strong> raduno Ragazzi\/Allievi, previsto domenica 17 novembre<\/strong>, <span style=\"text-decoration: underline\"><strong>&egrave; stato annullato<\/strong><\/span>.<\/p>\n<p>Intanto la <strong>squadra di Comitato<\/strong> si ritrover&agrave; ad <em><strong>Auronzo<\/strong><\/em> per tre giorni di lavoro (da venerd&igrave; 15 a domenica 17), presente anche l&#8217;allenatore azzurro<strong> Sepp Chenetti<\/strong>.<\/p>\n<p>Oltre ai componenti la squadra regionale, nell&#8217;occasione verr&agrave; aggregato <strong>Carlo Marchesin,<\/strong> da questa stagione esponente del <em><strong>GS 2002 Tarvisio<\/strong><\/em>.<\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto Aldo Plai<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La squadra di Comitato sa\u00e0 impegnata nel fine settimana ad Auronzo<\/p>\n","protected":false},"author":4,"featured_media":17447,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17446"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17446"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17446\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17447"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}