{"id":17341,"date":"2013-10-01T11:13:01","date_gmt":"2013-10-01T11:13:01","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/10\/01\/110-scialpinismo-prima-riunione-stagionale-per-la-commissione-fvg\/"},"modified":"2013-10-01T11:13:01","modified_gmt":"2013-10-01T11:13:01","slug":"110-scialpinismo-prima-riunione-stagionale-per-la-commissione-fvg","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/10\/01\/110-scialpinismo-prima-riunione-stagionale-per-la-commissione-fvg\/","title":{"rendered":"1\/10- SCIALPINISMO: prima riunione stagionale per la Commissione FVG"},"content":{"rendered":"<p><span style=\"font-family: mceinline\"><span style=\"text-decoration: underline;color: #ff0000\"><strong>1-10-2013<\/strong><\/span> Si &egrave; svolta ieri presso la sede CAI di Tolmezzo una riunione della <strong>Commissione scialpinismo dellao FISI FVG,<\/strong> promossa dal consigliere referente di specialit&agrave; per il Comitato<\/span><span style=\"font-family: mceinline\"><strong> Sergio Buricelli<\/strong>.<\/p>\n<p>L&#8217;incontro, al quale sono stati invitati tutti gli organizzatori delle gare di scialpinismo, aveva come punto principale la definizione del <strong>calendario FISI regionale 2013\/201<\/strong>4.<\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto i partecipanti alla riunione<\/strong><\/em><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ieri a Tolmezzo si \u00e8 parlato anche del calendario regionale 2013-2014<\/p>\n","protected":false},"author":4,"featured_media":17342,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17341"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17341"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17341\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17342"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}