{"id":17235,"date":"2013-08-20T14:10:33","date_gmt":"2013-08-20T14:10:33","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/08\/20\/208-combinata-parte-la-stagione-2013-2014-di-alessandro-pittin\/"},"modified":"2013-08-20T14:10:33","modified_gmt":"2013-08-20T14:10:33","slug":"208-combinata-parte-la-stagione-2013-2014-di-alessandro-pittin","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/08\/20\/208-combinata-parte-la-stagione-2013-2014-di-alessandro-pittin\/","title":{"rendered":"20\/8- COMBINATA: parte la stagione 2013-2014 di Alessandro Pittin"},"content":{"rendered":"<div class=\"field field-type-text field-field-news-testo1\">\n<div class=\"field-items\">\n<div class=\"field-item odd\">\n<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>20-8-2013<\/strong><\/span> Scatta nel weekend il Grand Prix di combinata nordica che presenta  nell&#8217;edizione 2013 tre tappe fra Oberwiesenthal sabato 24 e domenica 25  agosto con una team sprint e una Gundersen sui 10 km, a cui segue  l&#8217;appuntamento di Villach del 28 agosto con una Gundersen sui 10 km,  mentre la chiusura &egrave; prevista a Oberstdorf il 30-31 agosto con due  Gundersen sui 10 km e 15 km. Il torneo sperimenter&agrave; per la prima volta  la formula del &#8220;Weekend Challenge&#8221; che verr&agrave; introdotta nella prossima  edizione della Coppa del mondo, consistente in un minitour di un fine  settimana le cui tappe taglieranno il campo di partecipazione giorno  dopo giorno solamente ai migliori, aumentando il chilometraggio delle  frazioni nel fondo.<\/p>\n<p>Il direttore tecnico Ivo Pertile ha convocato per questo fine settimana  un quartetto composto da Samuel Costa, Manuel Maierhofer Armin Bauer e<strong> Alessandro Pittin<\/strong>. Ed &egrave; proprio il friulano il grande atteso della  prossima stagione di appuntamenti dopo due annate fortemente  condizionate da una lunga serie di infortuni (prima una doppia caduta in  allenamento che ha provocato la lesione al cercine della spalla  sinistra, seguita nello scorso dicembre dalla frattura dell&#8217;ulna e del  radio della mano sinistra), proprio quando pareva in lotta per la  classifica generale di Coppa del mondo. &#8220;In questi giorni mi sto  allenando dal trampolino di Villach &#8211; racconta il 23enne finanziere di  Cercivento -. Finora le cose stanno andando abbastanza bene sul fondo,  mentre sul salto manca ancora qualcosa. Siamo concentrati nel limare i  difetti, in questo periodo faccio fatica a trovare centralit&agrave; nella fase  di lancio che si riflette sulla spinta, cos&igrave; nella prima parte di volo  perdo velocit&agrave;&#8221;. La condizione atletica procede invece secondo  programma. &#8220;La spalla non ha recuperato del tutto la piena mobilit&agrave;,  continuando la fisioterapia la questione dovrebbe risolversi. Mi  piacerebbe tornare ad essere tra i migliori, cercheremo di partire bene  in Coppa del mondo perch&egrave; serve per il morale e per arrivare alle  Olimpiadi di Sochi con fiducia. Con la nuova formula del &#8220;Weekend  Challenge&#8221; aumenteranno le distanze nel fondo, ma coem sempre bisogner&agrave;  saltare bene per non perdere troppo terreno sugli sci stretti&#8221;.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il bronzo di Vancouver 2010 sar\u00e0 impegnato in Germania nel Grand Prix<\/p>\n","protected":false},"author":4,"featured_media":17236,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17235"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17235"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17235\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17236"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}