{"id":17233,"date":"2013-08-20T14:06:21","date_gmt":"2013-08-20T14:06:21","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/08\/20\/208-pietro-piller-cottrer-candidato-per-la-commissione-atleti-del-cio\/"},"modified":"2013-08-20T14:06:21","modified_gmt":"2013-08-20T14:06:21","slug":"208-pietro-piller-cottrer-candidato-per-la-commissione-atleti-del-cio","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/08\/20\/208-pietro-piller-cottrer-candidato-per-la-commissione-atleti-del-cio\/","title":{"rendered":"20\/8- Pietro Piller Cottrer candidato per la Commissione Atleti del CIO"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>20-8-2013 <\/strong><\/span>Nel corso dell&#8217;ultima riunione tenutasi a Mosca in occasione dei  Mondiali di atletica leggera, l&#8217;Executive Board del Comitato Olimpico  Internazionale ha approvato i nomi dei nove candidati per le elezioni  della Commissione Atleti che si terranno durante le Olimpiadi Invernali  di Sochi 2014. Nel prossimo febbraio saranno due i posti a disposizione  perch&egrave; Beckie Scott e Saku Koivu termineranno il loro mandato. Avranno  diritto di voto tutti gli atleti che prenderanno parte alle gare russe,  gli eletti rimarranno in carica per otto anni.<\/p>\n<p>Per l&#8217;Italia l&#8217;unico candidato &egrave; Pietro Piller Cottrer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; l&#8217;unico italiano. Le elezioni in occasione delle Olimpiadi di Sochi<\/p>\n","protected":false},"author":4,"featured_media":17234,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17233"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17233"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17234"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}