{"id":17223,"date":"2013-08-16T08:45:16","date_gmt":"2013-08-16T08:45:16","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/08\/16\/168-alpino-a-cervinia-lo-junior-stage-con-quattro-regionali\/"},"modified":"2013-08-16T08:45:16","modified_gmt":"2013-08-16T08:45:16","slug":"168-alpino-a-cervinia-lo-junior-stage-con-quattro-regionali","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/08\/16\/168-alpino-a-cervinia-lo-junior-stage-con-quattro-regionali\/","title":{"rendered":"16\/8- ALPINO: a Cervinia lo &#8220;Junior Stage&#8221; con quattro regionali"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>16-8-2013<\/strong><\/span> E&#8217; cominciato tra l&#8217;entusiasmo e l&#8217;emozione dei partecipanti il primo &#8220;<strong>Junior  stage<\/strong>&#8221; dello sci alpino sul ghiacciaio del Plateau Ros&agrave; di Cervinia. Alla  presenza significativa del presidente <strong>Flavio Roda <\/strong>che ha aperto il miniraduno di  quattro giorni, del direttore tecnico giovanile <strong>Alessandro Serra<\/strong> e dei  responsabili maschile e femminile <strong>Devid Salvadori <\/strong>e <strong>Roberto Lorenzi<\/strong>, ben 43  sciatori delle categorie Aspiranti e ultimo anno Allievi provenienti da tutti i  Comitati Regionali si sono messi di buona lena a disposizione  degli allenatori sulle due piste messe a disposizione dalla struttura sciistica,  con le ragazze impegnate in slalom e i ragazzi al lavoro in gigante.<\/p>\n<p>&#8220;Stiamo dando corpo ad un progetto per il quale lavoriamo da molti anni &#8211; ha  spiegato Serra -. Quest&#8217;anno lo abbiamo allargato a testimonianza dell&#8217;impegno  federale nel continuare a credere e investire sui giovani&#8221;. Tutti i partecipanti  al raduno hanno ricevuto in omaggio dal main sponsor tecnico Kappa una giacca  termica della nazionale italiana.&nbsp; <\/p>\n<p>Ricordiamo che il<strong> Comitato Friuli Venezia Giulia<\/strong>, in occasione di&nbsp;questa  importante vetrina giovanile,&nbsp;&egrave; rappresentato da quattro atleti, due femmine e  due maschi:&nbsp;<strong>Arianna Stocco, Greta Della Mea, Andrea Beltrame<\/strong> e<strong> Francesco  Gentilli<\/strong>, che si avvalgono del supporto dei selezionatori del Comitato <strong>Massimo  Lazzaro <\/strong>e <strong>Andrea Puicher Soravia<\/strong>.&nbsp;&nbsp; <\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto atleti e allenatori della Fisi Fvg a Cervinia<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il miniraduno si \u00e8 aperto alla presenza del presidente Flavio Roda<\/p>\n","protected":false},"author":4,"featured_media":17224,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17223"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17223"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17224"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}