{"id":17128,"date":"2013-07-14T10:58:35","date_gmt":"2013-07-14T10:58:35","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/07\/14\/147-freestyle-camilla-bledig-sul-podio-nel-waterjump-di-foederlach\/"},"modified":"2013-07-14T10:58:35","modified_gmt":"2013-07-14T10:58:35","slug":"147-freestyle-camilla-bledig-sul-podio-nel-waterjump-di-foederlach","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/07\/14\/147-freestyle-camilla-bledig-sul-podio-nel-waterjump-di-foederlach\/","title":{"rendered":"14\/7- FREESTYLE: Camilla Bledig sul podio nel Waterjump di Foederlach"},"content":{"rendered":"<p><!--[if gte mso 9]&gt;  Normal 0 14   false false false        MicrosoftInternetExplorer4  &lt;![endif]--><\/p>\n<p><!--[if gte mso 9]&gt;   &lt;![endif]--><!--[if !mso]&gt;--><\/p>\n<p>st1:*{behavior:url(#ieooui) }<\/p>\n<p><!--[if gte mso 10]&gt;--><\/p>\n<p> \/* Style Definitions *\/<br \/>\n table.MsoNormalTable<br \/>\n\t{mso-style-name:&#8221;Tabella normale&#8221;;<br \/>\n\tmso-tstyle-rowband-size:0;<br \/>\n\tmso-tstyle-colband-size:0;<br \/>\n\tmso-style-noshow:yes;<br \/>\n\tmso-style-parent:&#8221;&#8221;;<br \/>\n\tmso-padding-alt:0cm 5.4pt 0cm 5.4pt;<br \/>\n\tmso-para-margin:0cm;<br \/>\n\tmso-para-margin-bottom:.0001pt;<br \/>\n\tmso-pagination:widow-orphan;<br \/>\n\tfont-size:10.0pt;<br \/>\n\tfont-family:&#8221;Times New Roman&#8221;;<br \/>\n\tmso-ansi-language:#0400;<br \/>\n\tmso-fareast-language:#0400;<br \/>\n\tmso-bidi-language:#0400;}<\/p>\n<p class=\"MsoNormal\"><span style=\"text-decoration: underline;color: #ff0000\"><strong>14-7-2013<\/strong><\/span> Da met&agrave; giugno la Nazionale  A di freestyle (con <strong>Giacomo Matiz <\/strong>dell&#8217;<em><strong>US Aldo Moro<\/strong><\/em>) e il gruppo FuturFisi (del quale fanno parte i compagni di squadra <strong>Federico Vernier <\/strong>e <strong>Davide Zanier<\/strong>) sono al lavoro fra il ghiacciaio di Tignes in Francia e il centro sportivo di Tenero in Svizzera. In questa localit&agrave; trascorreranno 10 giorni di lavoro a secco ma soprattutto sar&agrave; intenso il lavoro di WaterJump (acrobatica dal trampolino con salti in piscina).<\/p>\n<p class=\"MsoNormal\">Oggi il gruppo regionale, seguito dall&rsquo;allenatore <strong>Stefano Vuerich<\/strong>, &egrave; impegnato a Tolmezzo per i consueti test atletici allo scopo di&nbsp; determinare la preparazione degli atleti e l&rsquo;eventuale programma di allenamenti a secco.<\/p>\n<p class=\"MsoNormal\">Da segnalare intanti la partecipazione ad un evento di WaterJump sia di Stefano Vuerich sia di <strong>Camilla Bledig,<\/strong> anch&#8217;essa dell&#8217;Aldo Moro; la manifestazione internazionale a Foederlach (Austria) ha visto presenti una cinquantina di atleti e in campo femminile la Bledig &egrave; salita sul podio conquistando il 3&deg; posto, preceduta solo da due ragazze austriache.<\/p>\n<p class=\"MsoNormal\"><span style=\"color: #00ff00\"><em><strong>nella foto Camilla Bledig premiata a Foederlach<\/strong><\/em><\/span><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Intanto le squadre nazionale, FuturFisi e regionale sono al lavoro<\/p>\n","protected":false},"author":4,"featured_media":17129,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17128"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17128"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17128\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17129"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}