{"id":17050,"date":"2013-06-13T16:24:54","date_gmt":"2013-06-13T16:24:54","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/06\/13\/136-freestyle-gli-azzurri-del-freesnow-a-cividale-e-moimacco\/"},"modified":"2013-06-13T16:24:54","modified_gmt":"2013-06-13T16:24:54","slug":"136-freestyle-gli-azzurri-del-freesnow-a-cividale-e-moimacco","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/06\/13\/136-freestyle-gli-azzurri-del-freesnow-a-cividale-e-moimacco\/","title":{"rendered":"13\/6- FREESTYLE: gli azzurri del freesnow a Cividale e Moimacco"},"content":{"rendered":"<div class=\"field field-type-text field-field-news-testo1\">\n<div class=\"field-items\">\n<div class=\"field-item odd\">\n<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>13-6-2013<\/strong><\/span> Riprende da Mettmenstetten, paesino del Cantone tedesco, la  preparazione della squadra di Gobbe guidata da Andrea Rinaldi. Il duo  storico composto da&nbsp; <strong>Giacomo Matiz<\/strong> e Deborah Scanzio si allener&agrave; nella  localit&agrave; svizzera fino a sabato 15 giugno e sar&agrave; in compagnia della  giovane ventenne lombarda Chiara Neujahr, messasi in evidenza nella  scorsa Coppa Europa e nei Mondiali juniores, a cui i tecnici hanno dato  la possibilit&agrave; di allenarsi con il gruppetto di Coppa del mondo.<\/p>\n<p>Il gruppo di Cdm di freesnow si allena invece fra <strong>Cividale <\/strong>e <strong>Moimacco <\/strong>fino a sabato 15 giugno con Marco Donzelli, <strong>Simon Gruber,<\/strong> Kevin Kok, Marco  Grigis e gli allenatori Giacomo Kratter, Fabrizio Piller Cottrer e  Freddy Romano. nella medesima localit&agrave; sono presenti anche i ragazzi del  gruppo FuturFisi con Andreas Bacher, Markus Eder, Lukas Schaefer,  Christoph Schenk, Yuri Silvestri, Ralph Welponer e Igor Lastei con il  responsabile Valentino Mori. <\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto Giacomo Matiz<\/strong><\/em><\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il raduno durer\u00e0 fino a sabato 15, mentre Giacomo Matiz lavora in Germania<\/p>\n","protected":false},"author":4,"featured_media":17051,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17050"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17050"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17050\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17051"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}