{"id":17012,"date":"2013-05-27T15:50:36","date_gmt":"2013-05-27T15:50:36","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/05\/27\/275-biathlon-gli-juniores-azzurri-in-raduno-a-forni-avoltri\/"},"modified":"2013-05-27T15:50:36","modified_gmt":"2013-05-27T15:50:36","slug":"275-biathlon-gli-juniores-azzurri-in-raduno-a-forni-avoltri","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/05\/27\/275-biathlon-gli-juniores-azzurri-in-raduno-a-forni-avoltri\/","title":{"rendered":"27\/5- BIATHLON: gli Juniores azzurri in raduno a Forni Avoltri"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>27-5-2013<\/strong><\/span> Il direttore tecnico della squadra nazionale di biathlon Fabrizio Curtaz ha convocato dieci atleti del  gruppo juniores per il raduno collegiale che si tiene al centro di sci nordico di Piani di Luzza, a <strong>Forni Avoltri<\/strong>, fino a sabato 1 giugno. <\/p>\n<p>Ecco i loro nomi: Carmen Runggaldier,  Martina Sirigu, <strong>Lisa Vittozzi<\/strong>, Xavier Guidetti, Saverio Zini, Andrea  Baretto, Andreas Plaikner, Federico Di Francesco, Luca Ghiglione, Maikol  Demetz. <\/p>\n<p>Al seguito della squadra ci sono il responsabile del progetto  FuturFisi <strong>Moreno Montello<\/strong> e i tecnici Nicola Pozzi e Barbara Ertl.<\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto Lisa Vittozzi<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel gruppo guidato da Moreno Montello c&#8217;\u00e8 anche la sappadina Lisa Vittozzi<\/p>\n","protected":false},"author":4,"featured_media":17013,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17012"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=17012"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/17012\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/17013"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=17012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=17012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=17012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}