{"id":16986,"date":"2013-05-11T13:12:19","date_gmt":"2013-05-11T13:12:19","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/05\/11\/115-sci-alpinismo-circuito-regionale-classifica-seniores-maschile\/"},"modified":"2013-05-11T13:12:19","modified_gmt":"2013-05-11T13:12:19","slug":"115-sci-alpinismo-circuito-regionale-classifica-seniores-maschile","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/05\/11\/115-sci-alpinismo-circuito-regionale-classifica-seniores-maschile\/","title":{"rendered":"11\/5- SCI ALPINISMO: circuito regionale, classifica Seniores maschile"},"content":{"rendered":"<p><span style=\"font-family: Tahoma;font-size: x-small\"><span style=\"font-family: Tahoma;font-size: x-small\"><span style=\"color: #ff0000;text-decoration: underline\"><strong>11-5-2013<\/strong><\/span> Proseguiamo la pubblicazione delle classifiche finali dei circuiti FISI FVG 2012-2013.<\/p>\n<p>A breve verranno pubblicate tutte le graduatorie di ogni singola categoria e specialit&agrave;.<\/p>\n<p>Oggi proponiamo la classifica<strong> SENIORES MASCHILE<\/strong> di <strong>SCI ALPINISMO.<\/strong><\/span><\/span><\/p>\n<p><span style=\"color: #0000ff\"><strong>1&nbsp;&nbsp;&nbsp; PIVK&nbsp;&nbsp;&nbsp; TADEI&nbsp;&nbsp;&nbsp; 81&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 600<\/strong><\/span><br \/><span style=\"color: #ff00ff\"><strong>2&nbsp;&nbsp;&nbsp; DEL MISSIER&nbsp;&nbsp;&nbsp; MARCO&nbsp;&nbsp;&nbsp; 74&nbsp;&nbsp;&nbsp; S.S. Fornese&nbsp;&nbsp;&nbsp; 531<\/strong><\/span><br \/><span style=\"color: #ff6600\"><strong>3&nbsp;&nbsp;&nbsp; MEIZINGER&nbsp;&nbsp;&nbsp; PAOLO&nbsp;&nbsp;&nbsp; 86&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 352<\/strong><\/span><br \/><em><strong>4&nbsp;&nbsp;&nbsp; CHIAVEDALE&nbsp;&nbsp;&nbsp; CRISTIAN&nbsp;&nbsp;&nbsp; 74&nbsp;&nbsp;&nbsp; S.S. Fornese&nbsp;&nbsp;&nbsp; 340<\/strong><\/em><br \/><em><strong>5&nbsp;&nbsp;&nbsp; PILLER HOFFER&nbsp;&nbsp;&nbsp; MATTEO&nbsp;&nbsp;&nbsp; 80&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 319<\/strong><\/em><br \/><em><strong>6&nbsp;&nbsp;&nbsp; DELLA MEA&nbsp;&nbsp;&nbsp; GIUSEPPE&nbsp;&nbsp;&nbsp; 87&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 316<\/strong><\/em><br \/><em><strong>7&nbsp;&nbsp;&nbsp; POIAZZI&nbsp;&nbsp;&nbsp; LUCA&nbsp;&nbsp;&nbsp; 70&nbsp;&nbsp;&nbsp; S.S. Velox Paularo&nbsp;&nbsp;&nbsp; 273<\/strong><\/em><br \/><em><strong>8&nbsp;&nbsp;&nbsp; FRATTINO&nbsp;&nbsp;&nbsp; SILVANO&nbsp;&nbsp;&nbsp; 90&nbsp;&nbsp;&nbsp; Sci Club Valcellina&nbsp;&nbsp;&nbsp; 238<\/strong><\/em><br \/><em><strong>9&nbsp;&nbsp;&nbsp; BITUSSI &nbsp;&nbsp;&nbsp; FEDERICO&nbsp;&nbsp;&nbsp; 81&nbsp;&nbsp;&nbsp; S.S. Fornese&nbsp;&nbsp;&nbsp; 229<\/strong><\/em><br \/><em><strong>10&nbsp;&nbsp;&nbsp; CANDOTTI&nbsp;&nbsp;&nbsp; DAMIANO&nbsp;&nbsp;&nbsp; 79&nbsp;&nbsp;&nbsp; Sci Club Sauris&nbsp;&nbsp;&nbsp; 22<\/strong><\/em>1<br \/>11&nbsp;&nbsp;&nbsp; DE FILIPPO&nbsp;&nbsp;&nbsp; ANTONIO&nbsp;&nbsp;&nbsp; 92&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 213<br \/>12&nbsp;&nbsp;&nbsp; CALLIGARIS&nbsp;&nbsp;&nbsp; MASSIMO&nbsp;&nbsp;&nbsp; 69&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 200<br \/>13&nbsp;&nbsp;&nbsp; PLESNIKAR&nbsp;&nbsp;&nbsp; FRANCO&nbsp;&nbsp;&nbsp; 69&nbsp;&nbsp;&nbsp; U.S. Raibl&nbsp;&nbsp;&nbsp; 181<br \/>14&nbsp;&nbsp;&nbsp; BETTIN&nbsp;&nbsp;&nbsp; MAURO&nbsp;&nbsp;&nbsp; 68&nbsp;&nbsp;&nbsp; Montanaia Racing&nbsp;&nbsp;&nbsp; 177<br \/>15&nbsp;&nbsp;&nbsp; LAZZARA&nbsp;&nbsp;&nbsp; PAOLO&nbsp;&nbsp;&nbsp; 82&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 172<br \/>16&nbsp;&nbsp;&nbsp; CAPOSASSI&nbsp;&nbsp;&nbsp; HERBERT&nbsp;&nbsp;&nbsp; 79&nbsp;&nbsp;&nbsp; S.S. Fornese&nbsp;&nbsp;&nbsp; 167<br \/>17&nbsp;&nbsp;&nbsp; MOROCUTTI&nbsp;&nbsp;&nbsp; GIONNI&nbsp;&nbsp;&nbsp; 73&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 146<br \/>18&nbsp;&nbsp;&nbsp; FERRARO&nbsp;&nbsp;&nbsp; ALESSANDRO&nbsp;&nbsp;&nbsp; 885&nbsp;&nbsp;&nbsp; Montanaia Racing&nbsp;&nbsp;&nbsp; 143<br \/>19&nbsp;&nbsp;&nbsp; BARATTIN&nbsp;&nbsp;&nbsp; RAUL&nbsp;&nbsp;&nbsp; 70&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 142<br \/>20&nbsp;&nbsp;&nbsp; TOME&#8217;&nbsp;&nbsp;&nbsp; GIANNI&nbsp;&nbsp;&nbsp; 80&nbsp;&nbsp;&nbsp; Sci Club Valcellina&nbsp;&nbsp;&nbsp; 131<br \/>21&nbsp;&nbsp;&nbsp; GIAZZON&nbsp;&nbsp;&nbsp; ROBERTO&nbsp;&nbsp;&nbsp; 74&nbsp;&nbsp;&nbsp; U.S. Raibl&nbsp;&nbsp;&nbsp; 122<br \/>21&nbsp;&nbsp;&nbsp; FEDELE&nbsp;&nbsp;&nbsp; MICHELE&nbsp;&nbsp;&nbsp; 75&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 122<br \/>23&nbsp;&nbsp;&nbsp; SEGRADO&nbsp;&nbsp;&nbsp; MARCO&nbsp;&nbsp;&nbsp; 72&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 118<br \/>24&nbsp;&nbsp;&nbsp; DI LENARDO&nbsp;&nbsp;&nbsp; ALESSANDRO&nbsp;&nbsp;&nbsp; 75&nbsp;&nbsp;&nbsp; U.S. Raibl&nbsp;&nbsp;&nbsp; 102<br \/>25&nbsp;&nbsp;&nbsp; ZANIER&nbsp;&nbsp;&nbsp; MICHELE&nbsp;&nbsp;&nbsp; 80&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 95<br \/>26&nbsp;&nbsp;&nbsp; MASTRACCHIO&nbsp;&nbsp;&nbsp; MICHELE&nbsp;&nbsp;&nbsp; 74&nbsp;&nbsp;&nbsp; Sci Club Weissenfels&nbsp;&nbsp;&nbsp; 94<br \/>27&nbsp;&nbsp;&nbsp; CARLOT&nbsp;&nbsp;&nbsp; FRANCO&nbsp;&nbsp;&nbsp; 68&nbsp;&nbsp;&nbsp; Sci Club Valcellina&nbsp;&nbsp;&nbsp; 92<br \/>28&nbsp;&nbsp;&nbsp; NASSIVERA&nbsp;&nbsp;&nbsp; MARCO&nbsp;&nbsp;&nbsp; 82&nbsp;&nbsp;&nbsp; S.S. Fornese&nbsp;&nbsp;&nbsp; 90<br \/>29&nbsp;&nbsp;&nbsp; CLERICI&nbsp;&nbsp;&nbsp; NICOLA&nbsp;&nbsp;&nbsp; 76&nbsp;&nbsp;&nbsp; S.S. Fornese&nbsp;&nbsp;&nbsp; 87<br \/>30&nbsp;&nbsp;&nbsp; MASCARIN&nbsp;&nbsp;&nbsp; MARC&nbsp;&nbsp;&nbsp; 69&nbsp;&nbsp;&nbsp; Montanaia Racing&nbsp;&nbsp;&nbsp; 81<br \/>30&nbsp;&nbsp;&nbsp; PICCOLI&nbsp;&nbsp;&nbsp; ALESSANDRO&nbsp;&nbsp;&nbsp; 72&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 81<br \/>32&nbsp;&nbsp;&nbsp; MELONI&nbsp;&nbsp;&nbsp; GIOVANNI&nbsp;&nbsp;&nbsp; 77&nbsp;&nbsp;&nbsp; U.S. Raibl&nbsp;&nbsp;&nbsp; 72<br \/>33&nbsp;&nbsp;&nbsp; SOLARI&nbsp;&nbsp;&nbsp; BRUNO&nbsp;&nbsp;&nbsp; 70&nbsp;&nbsp;&nbsp; G.S. Val Gleris&nbsp;&nbsp;&nbsp; 69<br \/>34&nbsp;&nbsp;&nbsp; MAINARDIS&nbsp;&nbsp;&nbsp; MAURIZIO&nbsp;&nbsp;&nbsp; 74&nbsp;&nbsp;&nbsp; S.S. Fornese&nbsp;&nbsp;&nbsp; 68<br \/>34&nbsp;&nbsp;&nbsp; ONGARO&nbsp;&nbsp;&nbsp; IVANO&nbsp;&nbsp;&nbsp; 80&nbsp;&nbsp;&nbsp; Montanaia Racing&nbsp;&nbsp;&nbsp; 68<br \/>36&nbsp;&nbsp;&nbsp; DE CRIGNIS&nbsp;&nbsp;&nbsp; CRISTIAN&nbsp;&nbsp;&nbsp; 83&nbsp;&nbsp;&nbsp; S.S. Velox Paularo&nbsp;&nbsp;&nbsp; 67<br \/>37&nbsp;&nbsp;&nbsp; NODALE&nbsp;&nbsp;&nbsp; DENIS&nbsp;&nbsp;&nbsp; 76&nbsp;&nbsp;&nbsp; S.S. Velox Paularo&nbsp;&nbsp;&nbsp; 64<br \/>37&nbsp;&nbsp;&nbsp; SILVERIO&nbsp;&nbsp;&nbsp; PAOLO&nbsp;&nbsp;&nbsp; 79&nbsp;&nbsp;&nbsp; S.S. Fornese&nbsp;&nbsp;&nbsp; 64<br \/>37&nbsp;&nbsp;&nbsp; NONIS&nbsp;&nbsp;&nbsp; DINO&nbsp;&nbsp;&nbsp; 71&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 64<br \/>40&nbsp;&nbsp;&nbsp; STEFANI&nbsp;&nbsp;&nbsp; MARCO&nbsp;&nbsp;&nbsp; 79&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 62<br \/>41&nbsp;&nbsp;&nbsp; MATARAZZO&nbsp;&nbsp;&nbsp; PIETRO&nbsp;&nbsp;&nbsp; 77&nbsp;&nbsp;&nbsp; Montanaia Racing&nbsp;&nbsp;&nbsp; 60<br \/>41&nbsp;&nbsp;&nbsp; MORASSI&nbsp;&nbsp;&nbsp; ALESSANDRO&nbsp;&nbsp;&nbsp; 76&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 60<br \/>43&nbsp;&nbsp;&nbsp; TARUSSIO&nbsp;&nbsp;&nbsp; GIOVANNI&nbsp;&nbsp;&nbsp; 71&nbsp;&nbsp;&nbsp; S.S. Velox Paularo&nbsp;&nbsp;&nbsp; 59<br \/>44&nbsp;&nbsp;&nbsp; SANSONETTI&nbsp;&nbsp;&nbsp; PAOLO&nbsp;&nbsp;&nbsp; 69&nbsp;&nbsp;&nbsp; Sci Club Valcellina&nbsp;&nbsp;&nbsp; 52<br \/>45&nbsp;&nbsp;&nbsp; TERRONI&nbsp;&nbsp;&nbsp; MARCO&nbsp;&nbsp;&nbsp; 68&nbsp;&nbsp;&nbsp; U.S. Raibl&nbsp;&nbsp;&nbsp; 50<br \/>46&nbsp;&nbsp;&nbsp; BUBISUTTI&nbsp;&nbsp;&nbsp; PAOLO&nbsp;&nbsp;&nbsp; 74&nbsp;&nbsp;&nbsp; S.S. Fornese&nbsp;&nbsp;&nbsp; 44<br \/>47&nbsp;&nbsp;&nbsp; FABRIS&nbsp;&nbsp;&nbsp; &nbsp;LUCA&nbsp;&nbsp;&nbsp; 71&nbsp;&nbsp;&nbsp; S.S. Fornese&nbsp;&nbsp;&nbsp; 42<br \/>47&nbsp;&nbsp;&nbsp; FERIGO&nbsp;&nbsp;&nbsp; SANDRO&nbsp;&nbsp;&nbsp; 78&nbsp;&nbsp;&nbsp; S.S. Velox Paularo&nbsp;&nbsp;&nbsp; 42<br \/>49&nbsp;&nbsp;&nbsp; DEREANI&nbsp;&nbsp;&nbsp; DORIS&nbsp;&nbsp;&nbsp; 86&nbsp;&nbsp;&nbsp; S.S. Velox Paularo&nbsp;&nbsp;&nbsp; 40<br \/>50&nbsp;&nbsp;&nbsp; TORTUL&nbsp;&nbsp;&nbsp; ENRICO&nbsp;&nbsp;&nbsp; 80&nbsp;&nbsp;&nbsp; U.S. Raibl&nbsp;&nbsp;&nbsp; 39<br \/>50&nbsp;&nbsp;&nbsp; LOZZA&nbsp;&nbsp;&nbsp; STEFANO&nbsp;&nbsp;&nbsp; 69&nbsp;&nbsp;&nbsp; S.S. Fornese&nbsp;&nbsp;&nbsp; 39<br \/>52&nbsp;&nbsp;&nbsp; ORLANDO &nbsp;&nbsp;&nbsp; PAOLO&nbsp;&nbsp;&nbsp; 84&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 37<br \/>53&nbsp;&nbsp;&nbsp; GERIN&nbsp;&nbsp;&nbsp; VALENTINO&nbsp;&nbsp;&nbsp; 85&nbsp;&nbsp;&nbsp; S.S. Velox Paularo&nbsp;&nbsp;&nbsp; 32<br \/>54&nbsp;&nbsp;&nbsp; BIASUTTI&nbsp;&nbsp;&nbsp; MICHELE&nbsp;&nbsp;&nbsp; 69&nbsp;&nbsp;&nbsp; Montanaia Racing&nbsp;&nbsp;&nbsp; 31<br \/>54&nbsp;&nbsp;&nbsp; STEFANUTO&nbsp;&nbsp;&nbsp; MARCO&nbsp;&nbsp;&nbsp; 74&nbsp;&nbsp;&nbsp; Montanaia Racing&nbsp;&nbsp;&nbsp; 31<br \/>56&nbsp;&nbsp;&nbsp; MOROCUTTI&nbsp;&nbsp;&nbsp; ANTONELLO&nbsp;&nbsp;&nbsp; 71&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 30<br \/>57&nbsp;&nbsp;&nbsp; MARINI&nbsp;&nbsp;&nbsp; GIUSEPPE&nbsp;&nbsp;&nbsp; 88&nbsp;&nbsp;&nbsp; Montanaia Racing&nbsp;&nbsp;&nbsp; 27<br \/>58&nbsp;&nbsp;&nbsp; SAVAGLIA&nbsp;&nbsp;&nbsp; LUIGI&nbsp;&nbsp;&nbsp; 84&nbsp;&nbsp;&nbsp; Montanaia Racing&nbsp;&nbsp;&nbsp; 25<br \/>59&nbsp;&nbsp;&nbsp; MAIER&nbsp;&nbsp;&nbsp; STEFANO&nbsp;&nbsp;&nbsp; 78&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 24<br \/>60&nbsp;&nbsp;&nbsp; ERRATH&nbsp;&nbsp;&nbsp; MARCO&nbsp;&nbsp;&nbsp; 75&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 23<br \/>61&nbsp;&nbsp;&nbsp; CEDOLIN&nbsp;&nbsp;&nbsp; LUCA&nbsp;&nbsp;&nbsp; 69&nbsp;&nbsp;&nbsp; S.S. Fornese&nbsp;&nbsp;&nbsp; 22<br \/>61&nbsp;&nbsp;&nbsp; LORENZI&nbsp;&nbsp;&nbsp; FRANCESCO&nbsp;&nbsp;&nbsp; 91&nbsp;&nbsp;&nbsp; Montanaia Racing&nbsp;&nbsp;&nbsp; 22<br \/>63&nbsp;&nbsp;&nbsp; CLAMA&nbsp;&nbsp;&nbsp; DANIEL&nbsp;&nbsp;&nbsp; 80&nbsp;&nbsp;&nbsp; S.S. Velox Paularo&nbsp;&nbsp;&nbsp; 21<br \/>63&nbsp;&nbsp;&nbsp; CACITTI&nbsp;&nbsp;&nbsp; MASSIMILIANO&nbsp;&nbsp;&nbsp; 79&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 21<br \/>65&nbsp;&nbsp;&nbsp; LAVARONI&nbsp;&nbsp;&nbsp; PAOLO&nbsp;&nbsp;&nbsp; 69&nbsp;&nbsp;&nbsp; U.S. Raibl&nbsp;&nbsp;&nbsp; 20<br \/>65&nbsp;&nbsp;&nbsp; PICOTTI&nbsp;&nbsp;&nbsp; CARLO&nbsp;&nbsp;&nbsp; 84&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 20<br \/>67&nbsp;&nbsp;&nbsp; LAZZARA&nbsp;&nbsp;&nbsp; MIRCO&nbsp;&nbsp;&nbsp; 78&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 19<br \/>67&nbsp;&nbsp;&nbsp; MARIN&nbsp;&nbsp;&nbsp; CHRISTIAN&nbsp;&nbsp;&nbsp; 74&nbsp;&nbsp;&nbsp; Montanaia Racing&nbsp;&nbsp;&nbsp; 19<br \/>69&nbsp;&nbsp;&nbsp; FUSETTI&nbsp;&nbsp;&nbsp; DAVIDE&nbsp;&nbsp;&nbsp; 71&nbsp;&nbsp;&nbsp; Montanaia Racing&nbsp;&nbsp;&nbsp; 18<br \/>69&nbsp;&nbsp;&nbsp; COMPASSI&nbsp;&nbsp;&nbsp; FEDERICO&nbsp;&nbsp;&nbsp; 78&nbsp;&nbsp;&nbsp; G.S. Val Gleris&nbsp;&nbsp;&nbsp; 18<br \/>69&nbsp;&nbsp;&nbsp; FRANZ&nbsp;&nbsp;&nbsp; JOSEF&nbsp;&nbsp;&nbsp; 83&nbsp;&nbsp;&nbsp; C.S. Creta Grauzaria&nbsp;&nbsp;&nbsp; 18<br \/>72&nbsp;&nbsp;&nbsp; DEL NEGRO&nbsp;&nbsp;&nbsp; ANDREA&nbsp;&nbsp;&nbsp; 72&nbsp;&nbsp;&nbsp; S.S. Velox Paularo&nbsp;&nbsp;&nbsp; 16<br \/>73&nbsp;&nbsp;&nbsp; GIORDANI&nbsp;&nbsp;&nbsp; DAMIANO&nbsp;&nbsp;&nbsp; 74&nbsp;&nbsp;&nbsp; Sci Club Valcellina&nbsp;&nbsp;&nbsp; 14<br \/>73&nbsp;&nbsp;&nbsp; MUSER&nbsp;&nbsp;&nbsp; DIEGO&nbsp;&nbsp;&nbsp; 78&nbsp;&nbsp;&nbsp; S.S. Fornese&nbsp;&nbsp;&nbsp; 14<br \/>73&nbsp;&nbsp;&nbsp; VISINTIN&nbsp;&nbsp;&nbsp; MARCO&nbsp;&nbsp;&nbsp; 76&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 14<br \/>76&nbsp;&nbsp;&nbsp; MASARIN&nbsp;&nbsp;&nbsp; MAURO&nbsp;&nbsp;&nbsp; 73&nbsp;&nbsp;&nbsp; Montanaia Racing&nbsp;&nbsp;&nbsp; 13<br \/>76&nbsp;&nbsp;&nbsp; TOSSUTTI&nbsp;&nbsp;&nbsp; MARCO&nbsp;&nbsp;&nbsp; 73&nbsp;&nbsp;&nbsp; Sci CAI XXX Ottobre&nbsp;&nbsp;&nbsp; 13<br \/>76&nbsp;&nbsp;&nbsp; CONCINA&nbsp;&nbsp;&nbsp; GIAN PAOLO&nbsp;&nbsp;&nbsp; 75&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 13<br \/>79&nbsp;&nbsp;&nbsp; INTERBARTOLO&nbsp;&nbsp;&nbsp; ANDREA&nbsp;&nbsp;&nbsp; 82&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 11<br \/>79&nbsp;&nbsp;&nbsp; SAPPADA&nbsp;&nbsp;&nbsp; DORIANO&nbsp;&nbsp;&nbsp; 70&nbsp;&nbsp;&nbsp; S.S. Velox Paularo&nbsp;&nbsp;&nbsp; 11<br \/>79&nbsp;&nbsp;&nbsp; VERGENDO&nbsp;&nbsp;&nbsp; MASSIMILIANO&nbsp;&nbsp;&nbsp; 82&nbsp;&nbsp;&nbsp; S.S. Velox Paularo&nbsp;&nbsp;&nbsp; 11<br \/>82&nbsp;&nbsp;&nbsp; BALESTRA&nbsp;&nbsp;&nbsp; ALESSANDRO&nbsp;&nbsp;&nbsp; 70&nbsp;&nbsp;&nbsp; G.S. Val Gleris&nbsp;&nbsp;&nbsp; 10<br \/>82&nbsp;&nbsp;&nbsp; BENZONI&nbsp;&nbsp;&nbsp; ALESSANDRO&nbsp;&nbsp;&nbsp; 71&nbsp;&nbsp;&nbsp; G.S. Val Gleris&nbsp;&nbsp;&nbsp; 10<br \/>82&nbsp;&nbsp;&nbsp; CATICCHIO&nbsp;&nbsp;&nbsp; MICHELE&nbsp;&nbsp;&nbsp; 82&nbsp;&nbsp;&nbsp; Montanaia Racing&nbsp;&nbsp;&nbsp; 10<br \/>85&nbsp;&nbsp;&nbsp; CLAMA&nbsp;&nbsp;&nbsp; MARCO&nbsp;&nbsp;&nbsp; 91&nbsp;&nbsp;&nbsp; S.S. Velox Paularo&nbsp;&nbsp;&nbsp; 9<br \/>85&nbsp;&nbsp;&nbsp; POIAZZI&nbsp;&nbsp;&nbsp; LUIGINO&nbsp;&nbsp;&nbsp; 68&nbsp;&nbsp;&nbsp; S.S. Velox Paularo&nbsp;&nbsp;&nbsp; 9<br \/>85&nbsp;&nbsp;&nbsp; SALA&nbsp;&nbsp;&nbsp; GIOVANNI&nbsp;&nbsp;&nbsp; 68&nbsp;&nbsp;&nbsp; S.S. Fornese&nbsp;&nbsp;&nbsp; 9<br \/>85&nbsp;&nbsp;&nbsp; SBRIZZAI&nbsp;&nbsp;&nbsp; GABRIEL&nbsp;&nbsp;&nbsp; 84&nbsp;&nbsp;&nbsp; S.S. Velox Paularo&nbsp;&nbsp;&nbsp; 9<br \/>89&nbsp;&nbsp;&nbsp; FABIANI&nbsp;&nbsp;&nbsp; ETTORE&nbsp;&nbsp;&nbsp; 74&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 8<br \/>89&nbsp;&nbsp;&nbsp; DE PRATO&nbsp;&nbsp;&nbsp; GIOV.BATTISTA&nbsp;&nbsp;&nbsp; 78&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 8<br \/>91&nbsp;&nbsp;&nbsp; FERIGO&nbsp;&nbsp;&nbsp; MARIO&nbsp;&nbsp;&nbsp; 91&nbsp;&nbsp;&nbsp; S.S. Velox Paularo&nbsp;&nbsp;&nbsp; 7<br \/>92&nbsp;&nbsp;&nbsp; SERENA&nbsp;&nbsp;&nbsp; PAOLO&nbsp;&nbsp;&nbsp; 68&nbsp;&nbsp;&nbsp; Sci Club Valcellina&nbsp;&nbsp;&nbsp; 6<br \/>93&nbsp;&nbsp;&nbsp; TURCHET&nbsp;&nbsp;&nbsp; LUCA&nbsp;&nbsp;&nbsp; 78&nbsp;&nbsp;&nbsp; Montanaia Racing&nbsp;&nbsp;&nbsp; 5<br \/>94&nbsp;&nbsp;&nbsp; DI RONCO&nbsp;&nbsp;&nbsp; FRANCESCO&nbsp;&nbsp;&nbsp; 68&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 3<br \/>95&nbsp;&nbsp;&nbsp; DE FRANCESCHI&nbsp;&nbsp;&nbsp; OSCAR&nbsp;&nbsp;&nbsp; 73&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 2<br \/>95&nbsp;&nbsp;&nbsp; GEROMETTA&nbsp;&nbsp;&nbsp; LORENZO&nbsp;&nbsp;&nbsp; 81&nbsp;&nbsp;&nbsp; S.S. Velox Paularo&nbsp;&nbsp;&nbsp; 2<br \/>97&nbsp;&nbsp;&nbsp; CHNESE&nbsp;&nbsp;&nbsp; IVAN&nbsp;&nbsp;&nbsp; 73&nbsp;&nbsp;&nbsp; S.S. Fornese&nbsp;&nbsp;&nbsp; 1<br \/>97&nbsp;&nbsp;&nbsp; CORADAZZI&nbsp;&nbsp;&nbsp; IVAN&nbsp;&nbsp;&nbsp; 78&nbsp;&nbsp;&nbsp; Sci Club Sauris&nbsp;&nbsp;&nbsp; 1<br \/>97&nbsp;&nbsp;&nbsp; IANICH&nbsp;&nbsp;&nbsp; MICHELE&nbsp;&nbsp;&nbsp; 76&nbsp;&nbsp;&nbsp; U.S. Aldo Moro&nbsp;&nbsp;&nbsp; 1<br \/>97&nbsp;&nbsp;&nbsp; PIAT&nbsp;&nbsp;&nbsp; LUIGI ALDO&nbsp;&nbsp;&nbsp; 69&nbsp;&nbsp;&nbsp; Montanaia Racing&nbsp;&nbsp;&nbsp; 1<br \/>97&nbsp;&nbsp;&nbsp; PICCO&nbsp;&nbsp;&nbsp; NORIS&nbsp;&nbsp;&nbsp; 69&nbsp;&nbsp;&nbsp; G.S. Val Gleris&nbsp;&nbsp;&nbsp; 1<br \/>97&nbsp;&nbsp;&nbsp; SCREM&nbsp;&nbsp;&nbsp; OTHMAR&nbsp;&nbsp;&nbsp; 80&nbsp;&nbsp;&nbsp; S.S. Velox Paularo&nbsp;&nbsp;&nbsp; 1<\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto Tadei Pivk<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tadei Pivk precede Marco Del Missier e Paolo Meizinger<\/p>\n","protected":false},"author":4,"featured_media":16987,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16986"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=16986"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16986\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/16987"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=16986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=16986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=16986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}