{"id":16970,"date":"2013-04-24T10:12:20","date_gmt":"2013-04-24T10:12:20","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/04\/24\/244-sci-paralimpico-bronzo-europeo-in-gigante-per-roberto-sartori\/"},"modified":"2013-04-24T10:12:20","modified_gmt":"2013-04-24T10:12:20","slug":"244-sci-paralimpico-bronzo-europeo-in-gigante-per-roberto-sartori","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/04\/24\/244-sci-paralimpico-bronzo-europeo-in-gigante-per-roberto-sartori\/","title":{"rendered":"24\/4- SCI PARALIMPICO: bronzo europeo in gigante per Roberto Sartori"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>24-4-2013<\/strong><\/span> Grande soddisfazione per i dirigenti, tecnici e soci della grande famiglia dello<strong> Sci Club Due<\/strong> dell&#8217;unione sportiva ACLI di Ronchi dei Legionari per la bella medaglia di bronzo conquistata nella gara di slalom gigante dal suo giovane atleta ipovedente ronchese <strong>Roberto Sartori <\/strong>nella seconda tappa dell&#8217;<em><strong>European Para Snow Sport Youth Circuit <\/strong><\/em>svoltasi sulle nevi slovene di Rogla, importante centro sciistico nei pressi di Maribor. Il bravo atleta ronchese, sapientemente guidato dal ventunenne maestro di sci<strong> Mattia Rozic<\/strong>, grazie alla regolarita delle due manche dello slalom gigante ha fatto sua cos&igrave; questa importante medaglia.<br \/>A questo particolare e singolare circuito di Europeo per atleti disabili, promosso dall&#8217;esecutivo dell IPC Alpine Skiing, hanno partecipato un centinaio di ragazzi, in rappresentanza di una decina di nazioni.<br \/>Dopo la prima tappa svoltasi sulle nevi spagnole di La Molina, il team ronchese, che per l&#8217;occasione rappresentava la squadra azzurra, con il suo giovane e bravo atleta ha centrato questo importante risultato arricchendo con questa medaglia europea il gi&agrave; blasonato medagliere del sodalizio.<br \/>Particolarmente soddisfatti il presidente<strong> Adriano Orsi<\/strong>, il coach<strong> Paolo Tavian<\/strong> e il coordinatore <strong>Fiorenzo Boscarol<\/strong>, perch&egrave; viene premiato un lungo e certosino lavoro iniziato nel 2008 e che ora sprona tutto lo staff ad un maggiore impegno in vista della prossima tappa programmata per fine novembre in Olanda.<br \/>Al bel risultato di Roberto va aggiunto la significativa prestazione di <strong>Riccardo Quargnolo<\/strong> della FAI Sport di Udine, un simpatico e vivace ragazzino di dieci anni cieco totale, che alla sua prima gara, sapientemente guidato da Enrico Poles, ha colto un onorevole quarto posto. Quanto mai importanti e determinanti poi gli allenamenti dei giorni precedenti curati dalle guide dello Sci Club Due, in particolare <strong>Marta Serafin<\/strong> e <strong>Alberto Zimolo<\/strong>; solo per un banale disguido al cancelletto di partenza la brava diciottenne non vedente totale <strong>Giulia Oblach <\/strong>non ha poturo concludere in bellezza la sua performance.<br \/>Simpatica e quanto mai apprezzata poi dalla nazionale slovena la disponibilit&agrave; dell&#8217;allievo maestro di sci Alberto Zimolo, che con perizia ha guidato il giovanisimo ipovedente sloveno <strong>Luka Keber<\/strong>, portandolo sul secondo gradino del podio.<br \/>Questo progetto europeo era stato programmato e seguito da alcuni responsabili della Federazione Italiana Paralimpica gi&agrave; da molti mesi, ma come spesso accade i progetti non sono stati sviluppati e conclusi. Solo poche settimane fa, dopo le gare di Coppa Europa di Tarvisio, ci sono stati dei contatti con il tecnico paralimpico Paolo Tavian che, vista la sua conoscenza degli ambienti internazionali, &egrave; stato incaricato direttamente dall&rsquo;IPC di programmare e seguire questo importante evento promozionale.<br \/>L&rsquo;evento prevede altre due tappe estere, una in Olanda in novembre ed una in Germania a gennaio, poi a marzo ci dovrebbe essere la finale a Sestriere in Italia.<br \/>Tavian &egrave; per&ograve; seriamente intenzionato a far spostare la tappa italiana nella nostra regione visto che, grazie al lavoro in particolare dello Sci Club Due, in occasione della tappa slovena &egrave; stato evitato l&rsquo;incidente diplomatico causato dalla &ldquo;sparizione&rdquo; degli incaricati italiani, che ad onor del vero si erano fatti sentire a poche ore dalla partenza e soltanto dopo che il gruppo ronchese si era organizzato. Scontata la risposta del club ronchese: &#8220;No grazie, siamo in grado di condurre in porto l&rsquo;iniziativa autonomamente&#8221;.<\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto il gruppo dei partecipanti alla manifestazione di Rogla<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Splendido risultato in Slovenia per il giovane atleta dello Sci Club Due<\/p>\n","protected":false},"author":4,"featured_media":16971,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16970"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=16970"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16970\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/16971"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=16970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=16970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=16970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}