{"id":16932,"date":"2013-04-06T17:32:37","date_gmt":"2013-04-06T17:32:37","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/04\/06\/64-alpino-criterium-nazionale-cuccioli-giorgia-mase-la-migliore-fvg\/"},"modified":"2013-04-06T17:32:37","modified_gmt":"2013-04-06T17:32:37","slug":"64-alpino-criterium-nazionale-cuccioli-giorgia-mase-la-migliore-fvg","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/04\/06\/64-alpino-criterium-nazionale-cuccioli-giorgia-mase-la-migliore-fvg\/","title":{"rendered":"6\/4- ALPINO: Criterium Nazionale Cuccioli, Giorgia Mas\u00e8 la migliore FVG"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>6-4-2013<\/strong><\/span> Prima giornata oggi a Cortina per il &#8220;<strong>Criterium Nazionale Cucciol<\/strong>i&#8221;, che vede presenti tanti piccoli sciatori della FISI FVG. <\/p>\n<p>Nella gimkana Cuccioli 1 femminile, vinta dalla bergamasca Alessia Guerinoni, 11. posto per <strong>Giorgia Mas&egrave;<\/strong> (<em><strong>XXX Ottobre<\/strong><\/em>) e 27. per <strong>Giulia Lidia Vidrigh <\/strong>(<em><\/em><strong><em>Lussari<\/em><\/strong>). Nella classifica per Comitati il FVG &egrave; settimo. <br \/>Nei Cuccioli 1 maschile il successo &egrave; andato all&#8217;altoatesino Rapael Schieder, mentre il migliore della FISI FVG &egrave; stato <strong>Giacomo Vidoni <\/strong>(<em><strong>Gs Sella Nevea<\/strong><\/em>), quattordicesimo. Fra i Comitati il nostro chiude sesto. <\/p>\n<p>Nello slalom 2 femminile, vinto dalla bolzanina Laura Auer, la prima del Comitato FVG &egrave; stata <strong>Ludovica Padulano<\/strong> (<em><strong>Gs Sella Nevea<\/strong><\/em>), trentaduesima. Il Comitato FVG &egrave; nono.<br \/>Tra i maschi si impone il bergamasco Francesco Bertocchi; 33. <strong>Paolo Palmegiano<\/strong> (<em><strong>Us Aldo Moro<\/strong><\/em>), con il Comitato FVG decimo.<\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto Giulia Lidia Vidrigh<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oggi a Cortina la prima giornata della manifestazione<\/p>\n","protected":false},"author":4,"featured_media":16933,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16932"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=16932"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16932\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/16933"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=16932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=16932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=16932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}