{"id":16880,"date":"2013-03-25T10:49:53","date_gmt":"2013-03-25T10:49:53","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/03\/25\/253-alpino-criterium-cuccioli-giovedi-28-allenamento-a-tarvisio\/"},"modified":"2013-03-25T10:49:53","modified_gmt":"2013-03-25T10:49:53","slug":"253-alpino-criterium-cuccioli-giovedi-28-allenamento-a-tarvisio","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/03\/25\/253-alpino-criterium-cuccioli-giovedi-28-allenamento-a-tarvisio\/","title":{"rendered":"25\/3- ALPINO: Criterium Cuccioli, gioved\u00ec 28 allenamento a Tarvisio"},"content":{"rendered":"<div><span style=\"font-family: Arial;font-size: x-small\"><span style=\"text-decoration: underline;color: #ff0000\">25-3-2013<\/span><strong> Gioved&igrave; 28 marzo<\/strong> si svolger&agrave; a  <strong>Tarvisio &#8211; Pista &#8220;C&#8221;<\/strong> un allenamento <strong>riservato  esclusivamente agli atleti&nbsp;della categoria Cuccioli 1 e 2 maschile e  femminile.&nbsp;selezionati a partecipare al 1&deg; Criterium Nazionale Cuccioli, in  programma a Cortina nei giorni 6 e 7 aprile.<\/strong><\/span><\/div>\n<div><span style=\"font-family: Arial;font-size: x-small\">L&#8217;allenamento &egrave; cos&igrave; programmato:<\/span><span style=\"font-family: Arial;font-size: x-small\"><strong><\/p>\n<p>&#8211; Ore 9.00:<\/strong> Ritrovo presso partenza    seggiovia doppia c\/o Pista &#8220;C&#8221;;<\/span><span style=\"font-family: Arial;font-size: x-small\"><strong><br \/>&#8211; Mattino:<\/strong> Allenamento di slalom    gigante;<\/span><span style=\"font-family: Arial;font-size: x-small\"><strong><br \/>&#8211; Pomeriggio:<\/strong> Allenamento di slalom    speciale.<\/span><\/div>\n<ul>\n<\/ul>\n<div><span style=\"font-family: Arial;font-size: x-small\">Si ringrazia il&nbsp;Direttore di Polo di Tarvisio  Alessandro Spaliviero per la&nbsp;disponibilit&agrave;.<\/span><\/div>\n<div><span style=\"font-family: Arial;font-size: x-small\">Per ogni&nbsp;eventuale necessit&agrave; e info  contattare&nbsp;Luca Destro al n. 366  1734856.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/span><\/div>\n<div>&nbsp;<\/div>\n<div><span style=\"font-family: Arial;font-size: x-small\"><em>Per la Commissione sci alpino <\/em><span style=\"color: #993300\"><strong>Tancredi Del  Mestre<\/strong><\/span><\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p><b>Il ritrovo presso la partenza della seggiovia doppia della Pista &#8220;C<\/b><\/p>\n","protected":false},"author":4,"featured_media":16881,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16880"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=16880"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16880\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/16881"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=16880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=16880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=16880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}