{"id":16872,"date":"2013-03-24T12:05:20","date_gmt":"2013-03-24T12:05:20","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/03\/24\/243-tadei-pivk-e-pietro-dalmasso-stelle-del-lussarissimo-2013\/"},"modified":"2013-03-24T12:05:20","modified_gmt":"2013-03-24T12:05:20","slug":"243-tadei-pivk-e-pietro-dalmasso-stelle-del-lussarissimo-2013","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/03\/24\/243-tadei-pivk-e-pietro-dalmasso-stelle-del-lussarissimo-2013\/","title":{"rendered":"24\/3- Tadei Pivk e Pietro Dalmasso stelle del Lussarissimo 2013"},"content":{"rendered":"<div style=\"margin: 0px;font: 12px Arial;color: #313131\"><span style=\"text-decoration: underline;color: #ff0000\"><strong>24-3-2013 <\/strong><\/span>La concorrenza  era agguerrita, come sempre, eppure <strong>Pietro Dalmasso<\/strong> ha fatto il bis. Lo sciatore  piemontese trapiantato in Veneto, infatti, si &egrave; aggiudicato, per il secondo  anno di seguito, il<strong> Lussarissimo Classic<\/strong>, il gigante parallelo sulla pista Di  Prampero sul Monte Lussari di <strong>Tarvisio<\/strong>, una delle pi&ugrave; belle delle Alpi. Un  &#8216;parallelo d&#8217;autore&#8217;, con oltre 100 porte sui 4 km del tracciato che in passato  ha ospitato anche la Coppa del Mondo di sci. Una manifestazione, quella del  Lussarissimo, giunta all&#8217;ottava edizione e che allo sci alpino abbina anche le  ciaspole (Ciaspolissima) e lo scialpinismo, con la gara vertical notturna Down  Up. &nbsp; Dalmasso ha fermato il cronometro sul tempo di 3.03.20, al secondo posto  l&#8217;austriaco Stefan Lussnig (3.06.74) e al terzo il &#8216;local&#8217; Francesco &#8216;Paco&#8217;  Veluscek (3.07.11). A seguire: Gabriele De Crignis, Samuel Borovinsek, Marco  Sandrini, Franz Thomas, Luca Menazzi, Matteo Menazzi. Questi ultimi, due  fratelli, si sono sfidati in un parallelo &#8216;all&#8217;ultima porta&#8217;. Tra le donne  successo dell&#8217;atleta slovena Ana Bucik (3.10.03), quest&#8217;anno terza nello slalom  di Coppa Europa di Vemdalen. Al secondo posto Giusy Rottonara e al terzo Barbara  Da Ros.<\/div>\n<div style=\"margin: 0px;font: 12px Arial;color: #313131\"><strong><br \/>LA GARA  CLASSIC<\/strong><\/div>\n<div style=\"margin: 0px;font: 12px Arial;color: #313131\">Pista tirata a  lucido, con tracciato che girava di pi&ugrave; rispetto all&#8217;anno scorso  (102 porte) che comunque ha retto abbastanza bene al passaggio dei tanti atleti  (250 iscritti). In media i concorrenti hanno fatto registrare tempi di 12-15  secondi superiori a quelli dell&#8217;anno scorso. &laquo;Non credevo di vincere ancora  contro tutti questi atleti giovani, sono molto soddisfatto, quando sono sceso io  la pista era quasi perfetta&raquo; ha detto al traguardo Pietro Dalmasso, che l&#8217;anno  scorso si &egrave; aggiudicato anche la classifica finale dell&#8217;Italian Ranking. &laquo;Ho  fatto veramente fatica&raquo; invece il commento di Stefan Lussnig. Francesco Veluscek  &egrave; stato probabilmente un po&#8217; penalizzato dalle condizioni della pista perch&eacute; &egrave;  sceso tra gli ultimi: &laquo;E&#8217; stata dura, alla fine la pista si era un po&#8217; segnata  ed ero stanco&raquo;. &laquo;La pista quando sono scesa io era molto bella, giusto le ultime  porte erano un po&#8217; segnate &#8211; ha detto la Bucik -. Conosco bene la Di Prampero,  anche se era la prima volta che partecipavo al Lussarissimo, perch&eacute; mi alleno  spesso qui e ho anche corso in Coppa Europa&raquo;.&nbsp;<\/div>\n<div style=\"margin: 0px;font: 12px Arial;color: #313131\"><strong><br \/>LA DOWN  UP<\/strong><\/div>\n<div style=\"margin: 0px;font: 12px Arial;color: #313131\">Duecentoventi  partecipanti per la ormai classicissima Lussarissimo Down Up, il vertical  notturno di scialpinismo di venerd&igrave; sera che ha aperto il fine settimana.  Quest&#8217;anno ha visto al via, oltre al favoritissimo<strong> Tadei Pivk,<\/strong> anche il forte  sloveno Nejc Kuhar, sulla carta i due atleti che potevano osare la vittoria. Una  gara che quest&#8217;anno presentava anche qualche incognita in pi&ugrave; perch&eacute;, a  differenza dell&#8217;anno scorso, quando fu corsa sulla pista di sci Di Prampero, a  causa dello scarso innevamento, si &egrave; svolta lungo il sentiero del Pellegrino.  Tracciato che&nbsp; quest&#8217;anno differiva da quello tradizionale nell&#8217;ultimo tratto,  che fa parte di un nuovo percorso per lo scialpinismo predisposto dalla  Promotur. Ultimo tratto che, a detta dei protagonisti, &egrave; stato quello pi&ugrave;  insidioso, con neve difficile e poca aderenza. Alla fine, sullo scenografico  traguardo del Monte Lussari, con tempo bello e temperatura di qualche grado  sotto lo zero, &egrave; transitato primo sempre lui, Tadei Pivk. con il tempo di 46&#8242;  28&#8221;, seguito proprio da Kuhar, al quale ha rifilato 2&#8242; 56&#8221; di distacco sul  tracciato di 5 km e 1.000 metri di dislivello. Pivk correva in casa, conosceva  benissimo il percorso, e questo &egrave; stato sicuramente un bel vantaggio, ma la  prestazione &egrave; stata notevole, a dimostrazione della grande stagione che sta  vivendo Tadei. Al terzo posto l&#8217;austriaco Niklas Kroehn, con 50&#8242; 30&#8221;. Nella top  ten, nell&#8217;ordine, anche Marco Del Missier, Silvio Wieltschnig, Paolo Meizinger,  Gino Caneva, Anze Senk, Alessandro Piccoli e Giuseppe Della Mea. Nella gara rosa  vittoria di Marita Kroehn, moglie di Niklas, che ha fermato il cronometro a  1h.04&#8242;.17&#8221;. Al secondo posto Anna Finizio (1h.07&#8217;42&#8221;) e al terzo Alessia  Kratter (1h08&#8217;38&#8221;). Da segnalare che quest&#8217;anno la competizione era aperta  anche alle ciaspole e il primo classificato Michele Ermacora (Gruppo sportivo  Aquileia) ha impiegato circa 12 minuti in pi&ugrave; di Pivk (per la precisione  58&#8217;21&#8221;). La prima donna con le ciaspole &egrave; stata la slovena Anja Stenove&#265;  (1h.15&#8242;.54&#8221;).&nbsp;Nella combinata Classic-Down Up (con la stessa attrezzatura) si &egrave;  imposto Silvio Wieltschnig su Tadei Pivk e Paolo Lavaroni, mentre nella  combinata rosa ha vinto Monica Franz.<\/div>\n<div style=\"margin: 0px;font: 12px Arial;color: #313131\"><strong>PREMI PER  TUTTI&nbsp;<\/strong><\/div>\n<div style=\"margin: 0px;font: 12px Arial;color: #313131\">Molto nutrita  la schiera degli sponsor che hanno permesso di dare ai concorrenti un pacco gara  interessante e tanti premi. Diversi anche i premi a estrazione e speciali come  quello al cinquantesimo classificato al centesimo e al centocinquantesimo&nbsp; Un  riconoscimento inoltre per i pi&ugrave; anziani partecipanti alla gara Classic: Duilio  Chiandussi, classe 1932 e Giuseppe Skert, 1936.&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 svolta a Tarvisio la tradizionale due giorni con gigantissimo e ski alp<\/p>\n","protected":false},"author":4,"featured_media":16873,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16872"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=16872"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16872\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/16873"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=16872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=16872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=16872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}