{"id":16864,"date":"2013-03-23T15:48:04","date_gmt":"2013-03-23T15:48:04","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/03\/23\/233-alpino-arianna-stocco-seconda-aspiranti-al-passo-rolle\/"},"modified":"2013-03-23T15:48:04","modified_gmt":"2013-03-23T15:48:04","slug":"233-alpino-arianna-stocco-seconda-aspiranti-al-passo-rolle","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/03\/23\/233-alpino-arianna-stocco-seconda-aspiranti-al-passo-rolle\/","title":{"rendered":"23\/3- ALPINO: Arianna Stocco seconda Aspiranti al Passo Rolle"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>23-3-2013<\/strong><\/span> Secondo posto Aspiranti per <strong>Arianna Stocco <\/strong>nel gigante <strong>Fis Njr<\/strong> disputato oggi a Passo Rolle.<\/p>\n<p>La lussarina, quinta assoluta, &egrave; stata preceduta di soli 28 centesimi dalla triestina Jacqueline Illy.<br \/>Nelle prime venti anche <strong>Noemi Noris<\/strong> (10a), <strong>Nicole Pinto <\/strong>(12a), <strong>Giulia Fior <\/strong>(13a), <strong>Beatrice Michelotti<\/strong> (16a) e <strong>Ylenia Sabidussi<\/strong> (20a).<\/p>\n<p>Fra i maschi il migliore dei regionali nelle classifica assoluta &egrave; stato <strong>Michele Messidoro<\/strong> (16&deg;), mentre <strong>Ludovico Piller Cottrer<\/strong> &egrave; giunto 19&deg; assoluto e 7&deg; Aspiranti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La lussarina quinta assoluta nel gigante FIS NJR<\/p>\n","protected":false},"author":4,"featured_media":16865,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16864"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=16864"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16864\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/16865"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=16864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=16864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=16864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}