{"id":16862,"date":"2013-03-23T15:17:24","date_gmt":"2013-03-23T15:17:24","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/03\/23\/233-biathlon-coppa-italia-baritussio-e-montello-quarti-nella-sprint\/"},"modified":"2013-03-23T15:17:24","modified_gmt":"2013-03-23T15:17:24","slug":"233-biathlon-coppa-italia-baritussio-e-montello-quarti-nella-sprint","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/03\/23\/233-biathlon-coppa-italia-baritussio-e-montello-quarti-nella-sprint\/","title":{"rendered":"23\/3- BIATHLON: Coppa Italia, Baritussio e Montello quarti nella Sprint"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>23-3-2013<\/strong><\/span> In contemporanea alla Sprint valida per i Campionati Italiani Assoluti di biathlon, oggi ad Anterselva si &egrave; svolta una prova d<strong>i Coppa Italia<\/strong> per il settore giovanile, sempre nello stesso format.<br \/>Il migliore degli esponenti della FISI FVG &egrave; stato ancora una volta <strong>Giuseppe Montello<\/strong> (<em><strong>Monte Coglians<\/strong><\/em>), fresco vincitore del titolo Juniores della Mass Start, oggi quarto, stesso risultato ottenuto nelle Giovani dalla compagna di squadra <strong>Ilaria Baritussio<\/strong>. <\/p>\n<p>Ecco gli altri piazzamenti dei nostri esponenti.<\/p>\n<p><strong>JUNIOR M<\/strong>: 6&deg; Raffaele Magi.<\/p>\n<p><strong>GIOVANI M<\/strong>: 7&deg; Filippo Fauner, 10&deg; Nicola Romanin.<\/p>\n<p><strong>GIOVANI F<\/strong>: 4a Ilaria Baritussio, 7a Marta Pugnetti, 10a Eleonora Morassi.<\/p>\n<p><strong>ASPIRANTI M<\/strong>: 10&deg; Daniele Cappellari, 21&deg; Elia Buzzo, 26&deg; Fabrizio Puntel.<\/p>\n<p><strong>ASPIRANTI F<\/strong>: 13a Ilaria Magi, 18a Eleonora Fauner, 21a Anna Pallober, 26a Lucia Del Fabbro.<\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto Ilaria Baritussio<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ad Anterselva podio sfiorato per i due esponenti dell&#8217;Asd Monte Coglians<\/p>\n","protected":false},"author":4,"featured_media":16863,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16862"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=16862"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16862\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/16863"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=16862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=16862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=16862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}