{"id":16796,"date":"2013-03-13T08:57:02","date_gmt":"2013-03-13T08:57:02","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/03\/13\/133-sci-alpinismo-annullata-la-sci-alpinistica-del-canin\/"},"modified":"2013-03-13T08:57:02","modified_gmt":"2013-03-13T08:57:02","slug":"133-sci-alpinismo-annullata-la-sci-alpinistica-del-canin","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/03\/13\/133-sci-alpinismo-annullata-la-sci-alpinistica-del-canin\/","title":{"rendered":"13\/3- SCI ALPINISMO: annullata la &#8220;Sci Alpinistica del Canin&#8221;"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>13-3-2013<\/strong> <\/span>L&#8217;Us Raibl, organizzatore della manifestazione, comunica che la &#8220;Sci Alpinistica del Canin&#8221;, prevista domenica 14 aprile a Sella Nevea, &egrave; stata cancellata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La comunicazione da parte degli organizzatori dell&#8217;US Raibl<\/p>\n","protected":false},"author":4,"featured_media":16797,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16796"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=16796"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16796\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/16797"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=16796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=16796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=16796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}