{"id":16758,"date":"2013-03-09T12:39:27","date_gmt":"2013-03-09T12:39:27","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/03\/09\/93-alpino-michele-messidoro-campione-italiano-cittadini-di-gigante\/"},"modified":"2013-03-09T12:39:27","modified_gmt":"2013-03-09T12:39:27","slug":"93-alpino-michele-messidoro-campione-italiano-cittadini-di-gigante","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/03\/09\/93-alpino-michele-messidoro-campione-italiano-cittadini-di-gigante\/","title":{"rendered":"9\/3- ALPINO: Michele Messidoro campione italiano Cittadini di gigante"},"content":{"rendered":"<p><span style=\"text-decoration: underline;color: #ff0000\"><strong>9-3-2013<\/strong><\/span> <span style=\"font-size: x-small\"><strong>Michele Messidoro<\/strong> dello <em><strong>Sci CAI XXX Ottobre<\/strong><\/em> si &egrave; aggiudicato il gigante maschile dei <strong>Campionati Italiani Cittadini<\/strong>, organizzati a <em><strong>Piancavallo<\/strong><\/em> dallo<strong> Sci Club Pordenone<\/strong>, che ha messo in palio il <em><strong>Trofeo &#8220;Alleanza Toro&#8221;<\/strong><\/em>.<\/span><\/p>\n<p><span style=\"font-size: x-small\">Sulla pista &#8220;Tublat&#8221; Messidoro ha preceduto du 0.52 il laziale Antonio Moriconi e di 0.53 la coppia veneta Mario Lovato-Marco Enrico Cirillo. <\/span><\/p>\n<p><span style=\"font-size: x-small\">La prova femminile &egrave; andata alla veneta Matilde Minotto con 0.21 sull&#8217;altoatesina Julia Catharina Agerer e di 0.30 sulla triestina dello Sc 18 Cortina Jaqueline Illy. Quarta <strong>Elena Graffi Brunoro<\/strong> del <em><strong>Gs Sella Nevea<\/strong><\/em>, quinta<strong> Greta Forgiarini <\/strong>del <em><strong>Cimenti<\/strong><\/em>.<\/span><\/p>\n<p><span style=\"font-size: x-small\">Lo Sci club Pordenone, al termine di queste due  intense giornate di gara, desidera pubblicamente ringraziare gli  uomini Promotur, nella persona di<strong> Enzo Sima,<\/strong> per la collaudata  capacit&agrave; tecnica nel gestire le competizioni  impegnative anche in situazioni climatiche  estreme.<br \/>Un grazie anche ai volontari e a tutti gli atleti che con la  loro presenza hanno dato lustro a questa manifestazione.<\/span><br \/><span style=\"color: #00ff00;font-size: x-small\"><em><strong><br \/>nella foto il podio per Comitati, con il FVG primo davanti a Veneto e Lazio\/Sardegna<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oggi l&#8217;esponente dello Sci CAI XXX Ottobre si \u00e8 imposto a Piancavallo<\/p>\n","protected":false},"author":4,"featured_media":16759,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16758"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=16758"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16758\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/16759"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=16758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=16758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=16758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}