{"id":16676,"date":"2013-03-02T13:35:06","date_gmt":"2013-03-02T13:35:06","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/03\/02\/23-alpino-circuito-despar-classifiche-gigante-ragazziallievi\/"},"modified":"2013-03-02T13:35:06","modified_gmt":"2013-03-02T13:35:06","slug":"23-alpino-circuito-despar-classifiche-gigante-ragazziallievi","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/03\/02\/23-alpino-circuito-despar-classifiche-gigante-ragazziallievi\/","title":{"rendered":"2\/3- ALPINO: circuito Despar, classifiche gigante Ragazzi\/Allievi"},"content":{"rendered":"<p><span style=\"color: #ff0000;text-decoration: underline\"><strong>2-3-2013<\/strong><\/span> Si &egrave; disputato oggi a <strong>Forni di Sopra<\/strong> un gigante Ragazzi\/Allievi del <strong>circuito regionale Despar<\/strong> organizzato dalla <strong>Societ&agrave; Sportiva Fornese<\/strong>.<\/p>\n<p>La prova ha assegnato il <em><strong>Trofeo &#8220;Zan&#8221;, <\/strong><\/em>vinto dallo <strong>Sci CAI XXX Ottobre<\/strong> su <strong>Sci CAI Monte Lussari <\/strong>e <strong>GS Sella Nevea<\/strong>.<\/p>\n<p>Successi nei Ragazzi di <strong>Lara Della Mea<\/strong> (Lussari) e <strong>Larsen Skerk<\/strong> (GS Sella Nevea), negli Allievi di<strong> Greta Della Mea <\/strong>(Lussari) e<strong> Andrea Beltrame<\/strong> (XXX Ottobre).<\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto Greta Della Mea<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><b>Oggi a Forni di Sopra la prova organizzata dalla Ss Fornese<\/b><\/p>\n","protected":false},"author":4,"featured_media":16677,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16676"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=16676"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16676\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media\/16677"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=16676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=16676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=16676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}