{"id":16654,"date":"2013-02-28T12:23:50","date_gmt":"2013-02-28T12:23:50","guid":{"rendered":"http:\/\/www.fisifvg.org\/2013\/02\/28\/282-alpino-arianna-stocco-bronzo-nel-superg-degli-italiani-aspiranti\/"},"modified":"2013-02-28T12:23:50","modified_gmt":"2013-02-28T12:23:50","slug":"282-alpino-arianna-stocco-bronzo-nel-superg-degli-italiani-aspiranti","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/blog\/2013\/02\/28\/282-alpino-arianna-stocco-bronzo-nel-superg-degli-italiani-aspiranti\/","title":{"rendered":"28\/2- ALPINO: Arianna Stocco bronzo nel superG degli Italiani Aspiranti"},"content":{"rendered":"<p><span style=\"color: #ff0000;text-decoration: underline\"><strong>28-2-2013<\/strong><\/span> Arriva la prima medaglia per il Comitato FISI FVG ai <strong>Campionati Italiani Aspiranti di sci alpino, <\/strong>organizzati dallo<strong> Sci Club 70<\/strong>.<\/p>\n<p>L&#8217;ha ottenuta <strong>Arianna Stocco <\/strong>dello <strong>Sci CAI Monte Lussari<\/strong>, terza nel supergigante femminile&nbsp;di Sella Nevea vinto dalla lombarda <strong>Costanza Oleggini <\/strong>sulla gardenese <strong>Melissa Perathoner<\/strong>.<\/p>\n<p>Per Arianna, prima della classe &#8217;96,&nbsp;studentessa\/atleta dello <strong>ski college &#8220;Bachmann&#8221;<\/strong> di Tarvisio, &egrave; la seconda medaglia tricolore consecutiva nel superG, dopo l&#8217;argento dell&#8217;anno passato.<\/p>\n<p>Bene anche <strong>Francesca Polentarutti<\/strong> del<em><strong> Cimenti<\/strong><\/em>, diciottesima. Da segnalare anche il 27&deg; posto di<strong> Elena Graffi Brunoro<\/strong> (<em><strong>Gs Sella Nevea<\/strong><\/em>) e il 29&deg; di <strong>Beatrice Michelotti<\/strong> (<em><strong>Bachmann<\/strong><\/em>).<\/p>\n<p>Il superG maschile &egrave; stato vinto dal valdostano <strong>Federico Paini<\/strong> sull&#8217;altoatesino <strong>Christoph Atz <\/strong>e sul lombardo <strong>Tommaso Sala.<\/strong><br \/>Primo esponente della FISI FVG <strong>Ludovico Piller Cottrer<\/strong> (<em><strong>Sci Club Sappada<\/strong><\/em>), venticinquesimo. <\/p>\n<p><span style=\"color: #00ff00\"><em><strong>nella foto il podio del superG femminile<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><b>A Sella Nevea arriva la prima medaglia per il Comitato FISI FVG<\/B><\/p>\n","protected":false},"author":4,"featured_media":16655,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[792],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16654"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/comments?post=16654"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/posts\/16654\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/media?parent=16654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/categories?post=16654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/friuli-venezia-giulia\/wp-json\/wp\/v2\/tags?post=16654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}