{"id":983398,"date":"2015-02-14T15:51:18","date_gmt":"2015-02-14T14:51:18","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=983398"},"modified":"2015-02-14T15:51:18","modified_gmt":"2015-02-14T14:51:18","slug":"sci-alpino-out-gli-atleti-del-comitato-fisi-alpi-centrali-nello-slalom-delle-universiadi","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2015\/02\/14\/sci-alpino-out-gli-atleti-del-comitato-fisi-alpi-centrali-nello-slalom-delle-universiadi\/","title":{"rendered":"SCI ALPINO: OUT GLI ATLETI DEL COMITATO FISI ALPI CENTRALI NELLO SLALOM DELLE UNIVERSIADI"},"content":{"rendered":"<p style=\"text-align: justify\">Ultima giornata sfortunata per gli atleti del Comitato FISI Alpi Centrali nello slalom speciale maschile che conclude l&#8217;edizione 2015 delle Universiadi di Sierra Nevada in Spagna. Tutti gli azzurri sono usciti nel corso della prima manche.<\/p>\n<p style=\"text-align: justify\">Lo svizzero Ramon Zenhaeusern ha vinto la gara. Secondo posto per lo slovacco Matej Falat con un ritardo di 3&#8243;68, bronzo allo sloveno Filip Mlinzek a 3&#8243;73.<\/p>\n<p style=\"text-align: justify\">Marco Cerottini<br \/>\nUfficio stampa Comitato FISI Alpi Centrali<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ultima giornata sfortunata per gli atleti del Comitato FISI Alpi Centrali nello slalom speciale maschile che conclude l&#8217;edizione 2015 delle Universiadi di Sierra Nevada in Spagna. Tutti gli azzurri sono usciti nel corso della prima manche. Lo svizzero Ramon Zenhaeusern ha vinto la gara. Secondo posto per lo slovacco Matej Falat con un ritardo di 3&#8243;68, bronzo allo sloveno Filip&hellip;<\/p>\n","protected":false},"author":4,"featured_media":886744,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/983398"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=983398"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/983398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/886744"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=983398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=983398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=983398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}