{"id":982799,"date":"2015-02-13T17:28:28","date_gmt":"2015-02-13T16:28:28","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=982799"},"modified":"2015-02-13T17:28:28","modified_gmt":"2015-02-13T16:28:28","slug":"sci-alpino-3-titoli-nazionali-master-a-falcade","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2015\/02\/13\/sci-alpino-3-titoli-nazionali-master-a-falcade\/","title":{"rendered":"SCI ALPINO MASTER: NEL SG 3 TITOLI NAZIONALI A FALCADE"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-982806 \" src=\"http:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2015\/02\/SG_Master.jpg\" alt=\"SG_Master\" width=\"249\" height=\"216\" srcset=\"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2015\/02\/SG_Master.jpg 758w, https:\/\/comitati.fisi.org\/alpi-centrali\/wp-content\/uploads\/sites\/25\/2015\/02\/SG_Master-300x260.jpg 300w\" sizes=\"(max-width: 249px) 100vw, 249px\" \/><\/p>\n<p>Sono iniziati oggi a <strong>Falcade<\/strong> i <strong>Campionati Italiani Master<\/strong> di sci alpino.<\/p>\n<p>Ottimi, anzi, superlativi i risultati conquistati dagli atleti che difendono i colori del Comitato FISI Alpi Centrali. Nella prova inaugurale di <strong>SuperG<\/strong> sono ben tre le medaglie d&#8217;oro conquistate dagli atleti lombardi.<\/p>\n<p>Nella prova femminile <strong>master C<\/strong>\u00a0prima piazza per <strong>Patrizia Spampati<\/strong> che difende i colori dello Sci Club Orezzo. Nella categoria <strong>Master B<\/strong> si impone l&#8217;alfiere dello sci club Ubi Banca Goggi <strong>Lorenzo Ferrari<\/strong>. Infine <strong>Paolo Lorati<\/strong>\u00a0dello Sci Club Pontedilegno vince il titolo tricolore nella categoria <strong>Master A<\/strong>.<\/p>\n<p style=\"text-align: center\"><strong><a title=\"Classifiche CI_MAS\" href=\"https:\/\/www.sciclubtreviso.it\/CIM_classifiche.php\" target=\"_blank\" rel=\"noopener\">Clicca qui per accedere alle classifiche<\/a><\/strong><\/p>\n<p>\u00a0Marco Cerottini<br \/>\nUfficio stampa Comitato FISI Alpi Centrali<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono iniziati oggi a Falcade i Campionati Italiani Master di sci alpino. Ottimi, anzi, superlativi i risultati conquistati dagli atleti che difendono i colori del Comitato FISI Alpi Centrali. Nella prova inaugurale di SuperG sono ben tre le medaglie d&#8217;oro conquistate dagli atleti lombardi. Nella prova femminile master C\u00a0prima piazza per Patrizia Spampati che difende i colori dello Sci Club&hellip;<\/p>\n","protected":false},"author":4,"featured_media":982798,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/982799"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=982799"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/982799\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/982798"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=982799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=982799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=982799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}