{"id":982792,"date":"2015-02-13T17:02:49","date_gmt":"2015-02-13T16:02:49","guid":{"rendered":"https:\/\/www.fisialpicentrali.it\/cms\/?p=982792"},"modified":"2015-02-13T17:02:49","modified_gmt":"2015-02-13T16:02:49","slug":"sci-alpino-alle-universiadi-la-martinelli-out-nella-seconda-manche","status":"publish","type":"post","link":"https:\/\/comitati.fisi.org\/alpi-centrali\/blog\/2015\/02\/13\/sci-alpino-alle-universiadi-la-martinelli-out-nella-seconda-manche\/","title":{"rendered":"SCI ALPINO: ALLE UNIVERSIADI LA MARTINELLI OUT NELLA SECONDA MANCHE"},"content":{"rendered":"<p style=\"text-align: justify\">La Norvegia trionfa nello slalom femminile valevole per le Universiadi di Sierra Nevada. La medaglia d&#8217;oro \u00e8 andata a Thea Grosvold che ha preceduto di 47 centesimi la tedesca Monica Huebner, bronzo alla canadese Eve Routhier a 61 centesimi. Fuori nella seconda manche la ventenne lecchese Gaia Martinelli, ventisettesima a met\u00e0 gara<\/p>\n<p style=\"text-align: justify\">Marco Cerottini<br \/>\nUfficio stampa Comitato FISI Alpi Centrali<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Norvegia trionfa nello slalom femminile valevole per le Universiadi di Sierra Nevada. La medaglia d&#8217;oro \u00e8 andata a Thea Grosvold che ha preceduto di 47 centesimi la tedesca Monica Huebner, bronzo alla canadese Eve Routhier a 61 centesimi. Fuori nella seconda manche la ventenne lecchese Gaia Martinelli, ventisettesima a met\u00e0 gara Marco Cerottini Ufficio stampa Comitato FISI Alpi Centrali<\/p>\n","protected":false},"author":4,"featured_media":886744,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,9,10,11],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/982792"}],"collection":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/comments?post=982792"}],"version-history":[{"count":0,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/posts\/982792\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media\/886744"}],"wp:attachment":[{"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/media?parent=982792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/categories?post=982792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comitati.fisi.org\/alpi-centrali\/wp-json\/wp\/v2\/tags?post=982792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}